{"id":148606,"date":"2025-05-08T16:23:38","date_gmt":"2025-05-08T14:23:38","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\/"},"modified":"2026-05-09T00:14:12","modified_gmt":"2026-05-08T22:14:12","slug":"peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\/","title":{"rendered":"peter pan e la sirena"},"content":{"rendered":"<p>Immagine tratta dal libro &ldquo;<strong><em>Peter Pan<\/em><\/strong>&rdquo; di <em>James Matthew Barrie<\/em> nella versione integrale e illustrata di <em>Massimiliano Frezzato<\/em>.<\/p>\n<p>Le <strong>immagini pi&ugrave; belle di Lavieri Edizioni<\/strong> sono stampate ad<strong> alta risoluzione<\/strong> e con <strong>inchiostri ecologici<\/strong> su <strong>cartoncino di pregio Fedrigoni<\/strong>.<\/p>\n<p><strong>Cornice in legno grezzo senza vetro.<\/strong><\/p>\n<p><strong>Autografato a matita.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 69&#215;40<\/p>\n<p class=\"autore\"><span>Author: <\/span>massimiliano frezzato<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>lavieri<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1746714216<\/p>\n","protected":false},"featured_media":160781,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2443],"product_tag":[],"class_list":{"0":"post-148606","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-literary-framework","7":"product_shipping_class-packaging","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>peter pan e la sirena - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"peter pan e la sirena\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 69x40Author: massimiliano frezzatoManufacturer: lavieriISBN: LDM1746714216\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:14:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/peter-pan-e-la-sirena-frezzato-69x40-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1205\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;52,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\\\/\",\"name\":\"peter pan e la sirena - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/peter-pan-e-la-sirena-frezzato-69x40-3.jpg\",\"datePublished\":\"2025-05-08T14:23:38+00:00\",\"dateModified\":\"2026-05-08T22:14:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/peter-pan-e-la-sirena-frezzato-69x40-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/peter-pan-e-la-sirena-frezzato-69x40-3.jpg\",\"width\":1205,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"peter pan e la sirena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"52.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1746714216\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"peter pan e la sirena - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\/","og_locale":"en_US","og_type":"article","og_title":"peter pan e la sirena","og_description":"Subtitle: cm 69x40Author: massimiliano frezzatoManufacturer: lavieriISBN: LDM1746714216","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:14:12+00:00","og_image":[{"width":1205,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/peter-pan-e-la-sirena-frezzato-69x40-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;52,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\/","name":"peter pan e la sirena - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/peter-pan-e-la-sirena-frezzato-69x40-3.jpg","datePublished":"2025-05-08T14:23:38+00:00","dateModified":"2026-05-08T22:14:12+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/peter-pan-e-la-sirena-frezzato-69x40-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/peter-pan-e-la-sirena-frezzato-69x40-3.jpg","width":1205,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/peter-pan-e-la-sirena-massimiliano-frezzato-ldm1746714216\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"peter pan e la sirena"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"52.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1746714216","product_condition":"new"},"df_price":52,"df_sale_price":"","df_regular_price":52,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/peter-pan-e-la-sirena-frezzato-69x40-3-300x174.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/148606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=148606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/160781"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=148606"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=148606"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=148606"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=148606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}