{"id":146511,"date":"2025-03-28T14:41:17","date_gmt":"2025-03-28T13:41:17","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\/"},"modified":"2026-05-09T00:16:20","modified_gmt":"2026-05-08T22:16:20","slug":"come-bere-acqua-di-mare-mariano-arnal-9788892725096","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\/","title":{"rendered":"come bere acqua di mare"},"content":{"rendered":"<p>Questo breve lavoro &egrave; il primo di una serie che l&rsquo;<em>Istituto di Idrologia Medica e Climatologia delle Canarie<\/em>, in collaborazione con la <em>Fondazione Aqua Maris<\/em>, intende diffondere il pi&ugrave; ampiamente possibile. In esso, il professor <em>Mariano Arnal<\/em> espone in modo semplice le <strong>caratteristiche dell&rsquo;acqua di mare<\/strong> e i suoi <strong>possibili utilizzi come integratore alimentare<\/strong> o per il <strong>trattamento di vari disturbi dell&rsquo;organismo<\/strong>.<\/p>\n<p>Non &egrave; facile trovarla nei supermercati, ma si trova nei migliori centri termali, nelle diete e nelle farmacie. E con un grande vantaggio rispetto alle altre acque: <strong>la sorgente da cui ottenerla &egrave; la pi&ugrave; abbondante e la pi&ugrave; accessibile<\/strong>. &Egrave; molto pi&ugrave; affidabile di quanto siamo stati indotti a credere, se sapete dove prenderla e come controllarla.<\/p>\n<p>L&rsquo;importante &egrave; saperla bere! Ciascuno dovrebbe sapere quale gli si addice, cos&igrave; come ciascuno deve sapere quali cibi, come, quando e in quali quantit&agrave; siano adatti a lui. Chi ha bisogno di curare la propria alimentazione per motivi di salute o di peso non ha dubbi al riguardo. &Egrave; l&igrave; che dobbiamo collocarci: nella dieta. Perch&eacute; <strong>per una dieta equilibrata le acque minerali sono diventate un elemento fondamentale<\/strong>.<\/p>\n<p>Tra queste, e per raggiungere lo stesso obiettivo, <strong>l&rsquo;acqua di mare occupa un posto di assoluto rilievo<\/strong>. D&rsquo;altra parte, ci sono molte informazioni sul suo uso fin dai tempi antichi &#8211; ad esempio quando viene applicata sotto forma di bagni. Tuttavia, <strong>&egrave; alla fine del XIX Secolo che <em>Ren&eacute; Quinton<\/em> getta le basi per le propriet&agrave; salutari dell&rsquo;acqua di mare somministrata come bevanda<\/strong>.<\/p>\n<p>Da quel momento ad oggi, sono state diverse le indagini che confermano l&rsquo;utilit&agrave; dell&rsquo;acqua di mare se utilizzata per via orale.<\/p>\n<p>Edizione: 2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>mariano arnal<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>om edizioni<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788892725096<\/p>\n","protected":false},"featured_media":146509,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2977],"product_tag":[],"class_list":{"0":"post-146511","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-environment-and-ecology","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>come bere acqua di mare - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"come bere acqua di mare\" \/>\n<meta property=\"og:description\" content=\"Author: mariano arnalPublisher: om edizioniISBN: 9788892725096\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:16:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/come-bere-acqua-di-mare-arnal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"738\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;12,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\\\/\",\"name\":\"come bere acqua di mare - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/come-bere-acqua-di-mare-arnal.jpg\",\"datePublished\":\"2025-03-28T13:41:17+00:00\",\"dateModified\":\"2026-05-08T22:16:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/come-bere-acqua-di-mare-arnal.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/come-bere-acqua-di-mare-arnal.jpg\",\"width\":500,\"height\":738},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"come bere acqua di mare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"12.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788892725096\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"come bere acqua di mare - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\/","og_locale":"en_US","og_type":"article","og_title":"come bere acqua di mare","og_description":"Author: mariano arnalPublisher: om edizioniISBN: 9788892725096","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:16:20+00:00","og_image":[{"width":500,"height":738,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/come-bere-acqua-di-mare-arnal.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;12,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\/","name":"come bere acqua di mare - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/come-bere-acqua-di-mare-arnal.jpg","datePublished":"2025-03-28T13:41:17+00:00","dateModified":"2026-05-08T22:16:20+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/come-bere-acqua-di-mare-arnal.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/come-bere-acqua-di-mare-arnal.jpg","width":500,"height":738},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/come-bere-acqua-di-mare-mariano-arnal-9788892725096\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"come bere acqua di mare"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"12.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788892725096","product_condition":"new"},"df_price":12,"df_sale_price":"","df_regular_price":12,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/come-bere-acqua-di-mare-arnal-203x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/146511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=146511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/146509"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=146511"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=146511"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=146511"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=146511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}