{"id":146305,"date":"2025-03-24T14:42:33","date_gmt":"2025-03-24T13:42:33","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\/"},"modified":"2026-07-11T00:27:50","modified_gmt":"2026-07-10T22:27:50","slug":"walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\/","title":{"rendered":"walrus plate (montgolfiers collection)"},"content":{"rendered":"<p><strong>Montgolfiers series<\/strong> &ndash; The <strong>puffer&rsquo;s toxin<\/strong> induces a <strong>trance-like state<\/strong>&hellip; <em>both the companions fly<\/em> high in armony.<\/p>\n<p>&ldquo;<em>These illustrations represent <strong>aquatic animals seen through a fantastic and extravagant lens<\/strong>, hyperbole of an enchanting marine world that we should know and safeguard.<\/em><\/p>\n<p><em>All <strong>illustrations <\/strong>are <strong>hand-made using a pencil<\/strong> and then refined with China ink. A <strong>high-resolution scan <\/strong>follows, to faithfully maintain the visual characteristics of the hand drawing<\/em>&rdquo;. <strong>Riccardo Capuzzo<\/strong><\/p>\n<p>This plate is made of <strong>finest Chinese porcelain<\/strong> and <strong>decorated in Italy<\/strong>.<\/p>\n<p>Diameter:<strong> 29 cm<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>riccardo capuzzo<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>aquatic creatures<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>4751038791342<\/p>\n","protected":false},"featured_media":146303,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2446],"product_tag":[],"class_list":{"0":"post-146305","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kitchen","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>walrus plate (montgolfiers collection) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"walrus plate (montgolfiers collection)\" \/>\n<meta property=\"og:description\" content=\"Author: riccardo capuzzoManufacturer: aquatic creaturesISBN: 4751038791342\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T22:27:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/piatto-tricheco-collezione-montgolfiers-aquatic-creatures.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"525\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;95,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\\\/\",\"name\":\"walrus plate (montgolfiers collection) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/piatto-tricheco-collezione-montgolfiers-aquatic-creatures.jpg\",\"datePublished\":\"2025-03-24T13:42:33+00:00\",\"dateModified\":\"2026-07-10T22:27:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/piatto-tricheco-collezione-montgolfiers-aquatic-creatures.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/piatto-tricheco-collezione-montgolfiers-aquatic-creatures.jpg\",\"width\":525,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"walrus plate (montgolfiers collection)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"95.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"4751038791342\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"walrus plate (montgolfiers collection) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\/","og_locale":"en_US","og_type":"article","og_title":"walrus plate (montgolfiers collection)","og_description":"Author: riccardo capuzzoManufacturer: aquatic creaturesISBN: 4751038791342","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T22:27:50+00:00","og_image":[{"width":525,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/piatto-tricheco-collezione-montgolfiers-aquatic-creatures.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;95,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\/","name":"walrus plate (montgolfiers collection) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/piatto-tricheco-collezione-montgolfiers-aquatic-creatures.jpg","datePublished":"2025-03-24T13:42:33+00:00","dateModified":"2026-07-10T22:27:50+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/piatto-tricheco-collezione-montgolfiers-aquatic-creatures.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/piatto-tricheco-collezione-montgolfiers-aquatic-creatures.jpg","width":525,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/walrus-plate-montgolfiers-collection-riccardo-capuzzo-4751038791342\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"walrus plate (montgolfiers collection)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"95.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"4751038791342","product_condition":"new"},"df_price":95,"df_sale_price":"","df_regular_price":95,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/piatto-tricheco-collezione-montgolfiers-aquatic-creatures-225x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/146305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=146305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/146303"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=146305"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=146305"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=146305"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=146305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}