{"id":143038,"date":"2025-01-28T15:21:01","date_gmt":"2025-01-28T14:21:01","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/venise-philip-plisson-9782732480237\/"},"modified":"2026-07-11T00:32:33","modified_gmt":"2026-07-10T22:32:33","slug":"venise-philip-plisson-9782732480237","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/venise-philip-plisson-9782732480237\/","title":{"rendered":"venise"},"content":{"rendered":"<p><em><strong>Sublimissime, S&eacute;r&eacute;nissime, mon reve est devenu mon addresse.<\/strong><\/em><\/p>\n<p><em>C&#8217;est un reve nourri de longue date: naviguer sur les canaux aux mille et une l&eacute;gendes, se perdre, se retrouver dans ce double labyrinthe de terre et d&#8217;eau, d&#8217;ombre et de lumi&egrave;re o&ugrave; s&#8217;agitent des silhouettes. Se promener, sans jamais mettre le pied &agrave; terre et explorer les lieux souvent secrets o&ugrave; Venise garde la memoire d&#8217;anciens hotes prestigieux. T&eacute;moin privil&eacute;gi&eacute; de la vie des habitants de Venise, j&#8217;ai embarqu&eacute; au petit matin avec les maraichers, les livreurs, les remorqueurs, les pilotes du port. De jour comme de nuit, je suis mont&eacute; &agrave; bord des unit&eacute;s de la police et des pompiers. Je me perds encore reguli&egrave;rement dans cet enchevetrement de 177 canaux et 442 ponts. A Venise, c&#8217;est sans aucun doute le seul endroit o&ugrave; il vaille la peine de se perdre.<\/em><\/p>\n<p><strong><em>Jamais &agrave; terre, Venise, je la caresse des yeux depuis mes bateaux.<\/em><\/strong><\/p>\n<p><em>Dans cette cit&eacute; unique, j&#8217;ai observ&eacute; que mes nuits sont plus belles et plus douces que mes jours. Quand mon &eacute;trave se glisse silencieusement dans cet &eacute;crin exceptionnel, j&#8217;ai le sentiment, certaines nuits, de me payer un acompte de paradis.&nbsp;<\/em>Tu peux mourir &agrave; Venise, tu peux aussi d&eacute;cider d&#8217;y renaitre<em>.<\/em><\/p>\n<p><em>Photographiquement Votre,<\/em><\/p>\n<p><em>Philip Plisson<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>sublimissime serenissime<\/p>\n<p class=\"autore\"><span>Author: <\/span>philip plisson<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>editions de la martiniere<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9782732480237<\/p>\n","protected":false},"featured_media":143036,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3110],"product_tag":[],"class_list":{"0":"post-143038","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-everything-else-italy-picture-books-tourism","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>venise - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/venise-philip-plisson-9782732480237\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"venise\" \/>\n<meta property=\"og:description\" content=\"Subtitle: sublimissime serenissimeAuthor: philip plissonPublisher: editions de la martiniereISBN: 9782732480237\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/venise-philip-plisson-9782732480237\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T22:32:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/venise-sublimissime-serenissime-philip-plisson-editions-de-la-martiniere.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"657\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;62,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/venise-philip-plisson-9782732480237\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/venise-philip-plisson-9782732480237\\\/\",\"name\":\"venise - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/venise-philip-plisson-9782732480237\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/venise-philip-plisson-9782732480237\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/venise-sublimissime-serenissime-philip-plisson-editions-de-la-martiniere.jpg\",\"datePublished\":\"2025-01-28T14:21:01+00:00\",\"dateModified\":\"2026-07-10T22:32:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/venise-philip-plisson-9782732480237\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/venise-philip-plisson-9782732480237\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/venise-philip-plisson-9782732480237\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/venise-sublimissime-serenissime-philip-plisson-editions-de-la-martiniere.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/venise-sublimissime-serenissime-philip-plisson-editions-de-la-martiniere.jpg\",\"width\":657,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/venise-philip-plisson-9782732480237\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"venise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"62.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9782732480237\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"venise - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/venise-philip-plisson-9782732480237\/","og_locale":"en_US","og_type":"article","og_title":"venise","og_description":"Subtitle: sublimissime serenissimeAuthor: philip plissonPublisher: editions de la martiniereISBN: 9782732480237","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/venise-philip-plisson-9782732480237\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T22:32:33+00:00","og_image":[{"width":657,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/venise-sublimissime-serenissime-philip-plisson-editions-de-la-martiniere.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;62,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/venise-philip-plisson-9782732480237\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/venise-philip-plisson-9782732480237\/","name":"venise - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/venise-philip-plisson-9782732480237\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/venise-philip-plisson-9782732480237\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/venise-sublimissime-serenissime-philip-plisson-editions-de-la-martiniere.jpg","datePublished":"2025-01-28T14:21:01+00:00","dateModified":"2026-07-10T22:32:33+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/venise-philip-plisson-9782732480237\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/venise-philip-plisson-9782732480237\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/venise-philip-plisson-9782732480237\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/venise-sublimissime-serenissime-philip-plisson-editions-de-la-martiniere.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/venise-sublimissime-serenissime-philip-plisson-editions-de-la-martiniere.jpg","width":657,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/venise-philip-plisson-9782732480237\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"venise"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"62.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9782732480237","product_condition":"new"},"df_price":62,"df_sale_price":"","df_regular_price":62,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/venise-sublimissime-serenissime-philip-plisson-editions-de-la-martiniere-282x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/143038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=143038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/143036"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=143038"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=143038"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=143038"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=143038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}