{"id":142579,"date":"2025-01-17T14:38:32","date_gmt":"2025-01-17T13:38:32","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\/"},"modified":"2026-05-09T00:20:04","modified_gmt":"2026-05-08T22:20:04","slug":"dieci-navi-per-la-salvezza-massimo-minella-9788842568650","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\/","title":{"rendered":"dieci navi per la salvezza"},"content":{"rendered":"<p><em>&laquo;Il mare come via di fuga, salvezza, occasione per ritrovare la libert&agrave; perduta. &Egrave; il mare scelto da decine di migliaia di ebrei che, negli anni Trenta, lasciarono un&rsquo;Europa preda dei totalitarismi per trovare rifugio su un&rsquo;altra sponda disposta ad accoglierli.&raquo;<\/em><\/p>\n<p><strong>Dalla presa del potere del nazismo &egrave; spietata la caccia agli ebrei<\/strong>. Anche un transatlantico, un traghetto, un battello possono rappresentare un&rsquo;opportunit&agrave; di fuga. Ed eccole, allora,&nbsp;<strong>dieci storie di navi che sono solo una pagina del tragico libro della guerra<\/strong>, sintetizzandone per&ograve; i sentimenti che, da una parte e dall&rsquo;altra, si materializzano: l&rsquo;odio, l&rsquo;orrore, la tenacia, il desiderio di libert&agrave;.<\/p>\n<p>Dal pi&ugrave; celebre&nbsp;<em>Rex <\/em>a sconosciute carrette del mare, queste navi diventano <strong>il rifugio e il veicolo per decine di migliaia di persone<\/strong> desiderose di trovare riparo dalla guerra e dalla follia umana. Molti ci sono riusciti, altri non ce l&rsquo;hanno fatta e ora riposano sul fondo del mare.<\/p>\n<p><strong>Una tragedia che va in scena sul mare e che continua a farci riflettere<\/strong>.<\/p>\n<p><strong>Prefazione di <em>Moni Ovadia<\/em>.<\/strong><\/p>\n<p>Edizione: 2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>storie di ebrei in fuga 1933-1941<\/p>\n<p class=\"autore\"><span>Author: <\/span>massimo minella<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Ugo Mursia Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788842568650<\/p>\n","protected":false},"featured_media":142581,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3051],"product_tag":[],"class_list":{"0":"post-142579","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-from-1919-to-1945","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>dieci navi per la salvezza - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"dieci navi per la salvezza\" \/>\n<meta property=\"og:description\" content=\"Subtitle: storie di ebrei in fuga 1933-1941Author: massimo minellaPublisher: Ugo Mursia EditoreISBN: 9788842568650\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:20:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dieci-navi-per-la-salvezza-minella-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"752\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;15,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\\\/\",\"name\":\"dieci navi per la salvezza - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/dieci-navi-per-la-salvezza-minella-1.jpg\",\"datePublished\":\"2025-01-17T13:38:32+00:00\",\"dateModified\":\"2026-05-08T22:20:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/dieci-navi-per-la-salvezza-minella-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/dieci-navi-per-la-salvezza-minella-1.jpg\",\"width\":500,\"height\":752},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"dieci navi per la salvezza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"15.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788842568650\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"dieci navi per la salvezza - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\/","og_locale":"en_US","og_type":"article","og_title":"dieci navi per la salvezza","og_description":"Subtitle: storie di ebrei in fuga 1933-1941Author: massimo minellaPublisher: Ugo Mursia EditoreISBN: 9788842568650","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:20:04+00:00","og_image":[{"width":500,"height":752,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dieci-navi-per-la-salvezza-minella-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;15,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\/","name":"dieci navi per la salvezza - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dieci-navi-per-la-salvezza-minella-1.jpg","datePublished":"2025-01-17T13:38:32+00:00","dateModified":"2026-05-08T22:20:04+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dieci-navi-per-la-salvezza-minella-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dieci-navi-per-la-salvezza-minella-1.jpg","width":500,"height":752},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/dieci-navi-per-la-salvezza-massimo-minella-9788842568650\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"dieci navi per la salvezza"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"15.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788842568650","product_condition":"new"},"df_price":15,"df_sale_price":"","df_regular_price":15,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/dieci-navi-per-la-salvezza-minella-1-199x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/142579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=142579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/142581"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=142579"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=142579"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=142579"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=142579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}