{"id":141737,"date":"2024-12-22T11:22:21","date_gmt":"2024-12-22T10:22:21","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/quadro-precious-corales-rosso-su-carta-antica-la-casa-della-stampa-cdsm180antrq\/"},"modified":"2026-07-11T00:33:42","modified_gmt":"2026-07-10T22:33:42","slug":"quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\/","title":{"rendered":"quadro &#8220;precious corales rosso su carta antica&#8221;"},"content":{"rendered":"<p>Foglio di <strong>carta antica originale con testo recto e verso<\/strong>, su cui &egrave; stata impressa con il <strong>torchio a mano<\/strong> la <strong>riproduzione di una stampa antica<\/strong> (originale tratto da &ldquo;<em>Encyclop&eacute;die ou Dictionnaire raisonn&eacute; des sciences, des arts et des m&eacute;tiers&rdquo; di Diderot e D&rsquo;Alembert<\/em>), <strong>acquarellata a mano<\/strong> da pittori esperti.<\/p>\n<p><strong>Cornice in legno vetro su vetro.<\/strong><\/p>\n<p>Prodotto artigianale.<\/p>\n<p>Made in Italy.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 26&#215;37<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>La Casa della Stampa<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>CDSM180ANTRQ<\/p>\n","protected":false},"featured_media":150959,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2904],"product_tag":[],"class_list":{"0":"post-141737","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-other-animals","7":"product_shipping_class-packaging","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>quadro &quot;precious corales rosso su carta antica&quot; - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"quadro &quot;precious corales rosso su carta antica&quot;\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 26x37Manufacturer: La Casa della StampaISBN: CDSM180ANTRQ\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T22:33:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-precious-corales-rosso-su-carta-antica-m180-28x38-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;118,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\\\/\",\"name\":\"quadro \\\"precious corales rosso su carta antica\\\" - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/quadro-precious-corales-rosso-su-carta-antica-m180-28x38-2.jpg\",\"datePublished\":\"2024-12-22T10:22:21+00:00\",\"dateModified\":\"2026-07-10T22:33:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/quadro-precious-corales-rosso-su-carta-antica-m180-28x38-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/quadro-precious-corales-rosso-su-carta-antica-m180-28x38-2.jpg\",\"width\":500,\"height\":701},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"quadro &#8220;precious corales rosso su carta antica&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"118.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"CDSM180ANTRQ\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"quadro \"precious corales rosso su carta antica\" - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\/","og_locale":"en_US","og_type":"article","og_title":"quadro \"precious corales rosso su carta antica\"","og_description":"Subtitle: cm 26x37Manufacturer: La Casa della StampaISBN: CDSM180ANTRQ","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T22:33:42+00:00","og_image":[{"width":500,"height":701,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-precious-corales-rosso-su-carta-antica-m180-28x38-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;118,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\/","name":"quadro \"precious corales rosso su carta antica\" - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-precious-corales-rosso-su-carta-antica-m180-28x38-2.jpg","datePublished":"2024-12-22T10:22:21+00:00","dateModified":"2026-07-10T22:33:42+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-precious-corales-rosso-su-carta-antica-m180-28x38-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-precious-corales-rosso-su-carta-antica-m180-28x38-2.jpg","width":500,"height":701},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/quadro-precious-corales-rosso-su-carta-antica-cdsm180antrq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"quadro &#8220;precious corales rosso su carta antica&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"118.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"CDSM180ANTRQ","product_condition":"new"},"df_price":118,"df_sale_price":"","df_regular_price":118,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-precious-corales-rosso-su-carta-antica-m180-28x38-2-214x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/141737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=141737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/150959"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=141737"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=141737"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=141737"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=141737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}