{"id":140089,"date":"2024-11-25T16:28:10","date_gmt":"2024-11-25T15:28:10","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/capitan-natale-karl-newson-tom-knight-9791280031723\/"},"modified":"2026-05-09T00:21:44","modified_gmt":"2026-05-08T22:21:44","slug":"capitan-natale-karl-newson-tom-knight-9791280031723","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-natale-karl-newson-tom-knight-9791280031723\/","title":{"rendered":"capitan natale"},"content":{"rendered":"<p><strong>Sapevi che, un tempo, gli elfi di Babbo Natale erano dei temibili pirati?<\/strong><\/p>\n<p>Solcavano i mari e assaltavano le navi, in cerca di oro e tesori&hellip; Finch&eacute;, un giorno, <strong>tutto cambi&ograve; quando sul loro cammino incontrarono Capitan Natale, un allegro pirata che insegn&ograve; loro che &egrave; molto pi&ugrave; bello dare che ricevere<\/strong>.<\/p>\n<p>Da allora, nella notte pi&ugrave; magica dell&rsquo;anno attraversano montagne e oceani per consegnare doni a tutti i bambini. <strong>Preparati a conoscere la vera storia di Babbo Natale!<\/strong><\/p>\n<p>Et&agrave;: 4+<\/p>\n<p>Edizione: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>karl newson &#8211; tom knight<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Picarona<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9791280031723<\/p>\n","protected":false},"featured_media":140087,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2614],"product_tag":[],"class_list":{"0":"post-140089","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-illustrated-books-and-fiction","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>capitan natale - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/capitan-natale-karl-newson-tom-knight-9791280031723\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"capitan natale\" \/>\n<meta property=\"og:description\" content=\"Author: karl newson - tom knightPublisher: PicaronaISBN: 9791280031723\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/capitan-natale-karl-newson-tom-knight-9791280031723\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:21:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/capitan-natale-newson-knight.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"627\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;15,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/capitan-natale-karl-newson-tom-knight-9791280031723\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/capitan-natale-karl-newson-tom-knight-9791280031723\\\/\",\"name\":\"capitan natale - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/capitan-natale-karl-newson-tom-knight-9791280031723\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/capitan-natale-karl-newson-tom-knight-9791280031723\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/capitan-natale-newson-knight.jpg\",\"datePublished\":\"2024-11-25T15:28:10+00:00\",\"dateModified\":\"2026-05-08T22:21:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/capitan-natale-karl-newson-tom-knight-9791280031723\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/capitan-natale-karl-newson-tom-knight-9791280031723\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/capitan-natale-karl-newson-tom-knight-9791280031723\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/capitan-natale-newson-knight.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/capitan-natale-newson-knight.jpg\",\"width\":627,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/capitan-natale-karl-newson-tom-knight-9791280031723\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"capitan natale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"15.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9791280031723\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"capitan natale - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-natale-karl-newson-tom-knight-9791280031723\/","og_locale":"en_US","og_type":"article","og_title":"capitan natale","og_description":"Author: karl newson - tom knightPublisher: PicaronaISBN: 9791280031723","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-natale-karl-newson-tom-knight-9791280031723\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:21:44+00:00","og_image":[{"width":627,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/capitan-natale-newson-knight.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;15,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-natale-karl-newson-tom-knight-9791280031723\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-natale-karl-newson-tom-knight-9791280031723\/","name":"capitan natale - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-natale-karl-newson-tom-knight-9791280031723\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-natale-karl-newson-tom-knight-9791280031723\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/capitan-natale-newson-knight.jpg","datePublished":"2024-11-25T15:28:10+00:00","dateModified":"2026-05-08T22:21:44+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-natale-karl-newson-tom-knight-9791280031723\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/capitan-natale-karl-newson-tom-knight-9791280031723\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-natale-karl-newson-tom-knight-9791280031723\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/capitan-natale-newson-knight.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/capitan-natale-newson-knight.jpg","width":627,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-natale-karl-newson-tom-knight-9791280031723\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"capitan natale"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"15.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9791280031723","product_condition":"new"},"df_price":15,"df_sale_price":"","df_regular_price":15,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/capitan-natale-newson-knight-269x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/140089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=140089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/140087"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=140089"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=140089"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=140089"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=140089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}