{"id":139240,"date":"2024-11-05T18:47:04","date_gmt":"2024-11-05T17:47:04","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/intuizione-selvaggia-craig-foster-9791259853929\/"},"modified":"2026-05-09T00:22:21","modified_gmt":"2026-05-08T22:22:21","slug":"intuizione-selvaggia-craig-foster-9791259853929","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/intuizione-selvaggia-craig-foster-9791259853929\/","title":{"rendered":"intuizione selvaggia"},"content":{"rendered":"<p><strong>Dall&rsquo;autore del documentario premio Oscar <em>Il mio amico in fondo al mare<\/em>.<\/strong><\/p>\n<p>Al tempo stesso <strong>storia d&rsquo;amore e di avventura, diario di viaggio, memoir naturalistico e guida spirituale<\/strong>, <em>Intuizione selvaggia<\/em> &egrave; la straordinaria testimonianza di come sia possibile <strong>recuperare una profonda connessione con una parte del nostro io<\/strong> che non siamo pi&ugrave; abituati ad ascoltare, ma che pu&ograve; dare un senso nuovo alle nostre vite.<\/p>\n<p>Craig Foster, regista e fotografo naturalista, racconta il lungo percorso di <em>rinaturalizzazione<\/em> e rinascita iniziato nel Deserto del Kalahari e culminato nel luogo in cui &egrave; nato, la costa del <strong>Capo di Buona Speranza<\/strong>. <strong>Immergersi nelle profondit&agrave; della grande foresta oceanica africana l&rsquo;ha aiutato a riscoprire la sua <em>anima anfibia<\/em><\/strong> e a vederla come una potente metafora della condizione umana: noi homines sapientes siamo per natura animali selvaggi che tentano di esistere in un mondo addomesticato. Ma c&rsquo;&egrave; una parte di noi che possiamo recuperare&#8230;<\/p>\n<p>Che viviamo vicino alla natura o in una giungla urbana, Craig Foster ci sfida a riflettere sul nostro <strong>rapporto personale con la natura<\/strong>, a seguirne le tracce e a ristabilire una profonda <strong>connessione con la nostra essenza selvaggia<\/strong>. Perch&eacute; solo cos&igrave; riusciremo a vivere in armonia con ci&ograve; che ci circonda.<\/p>\n<p>Edizione: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>abbraccia la tua anima ancestrale e impara dalla natura come vivere in equilibrio nel mondo di oggi<\/p>\n<p class=\"autore\"><span>Author: <\/span>craig foster<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>harpercollins italia<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9791259853929<\/p>\n","protected":false},"featured_media":139242,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2977,3100,2589],"product_tag":[],"class_list":{"0":"post-139240","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-environment-and-ecology","7":"product_cat-essays-diving","8":"product_cat-books-diving-literature","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>intuizione selvaggia - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/intuizione-selvaggia-craig-foster-9791259853929\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"intuizione selvaggia\" \/>\n<meta property=\"og:description\" content=\"Subtitle: abbraccia la tua anima ancestrale e impara dalla natura come vivere in equilibrio nel mondo di oggiAuthor: craig fosterPublisher: harpercollins italiaISBN: 9791259853929\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/intuizione-selvaggia-craig-foster-9791259853929\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:22:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/intuizione-selvaggia-abbraccia-la-tua-anima-ancestrale-e-impara-dalla-natura-come-vivere-in-equilibrio-nel-mondo-di-oggi-craig-foster-harpercollins-italia-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;19,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/intuizione-selvaggia-craig-foster-9791259853929\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/intuizione-selvaggia-craig-foster-9791259853929\\\/\",\"name\":\"intuizione selvaggia - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/intuizione-selvaggia-craig-foster-9791259853929\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/intuizione-selvaggia-craig-foster-9791259853929\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/intuizione-selvaggia-abbraccia-la-tua-anima-ancestrale-e-impara-dalla-natura-come-vivere-in-equilibrio-nel-mondo-di-oggi-craig-foster-harpercollins-italia-1.jpg\",\"datePublished\":\"2024-11-05T17:47:04+00:00\",\"dateModified\":\"2026-05-08T22:22:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/intuizione-selvaggia-craig-foster-9791259853929\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/intuizione-selvaggia-craig-foster-9791259853929\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/intuizione-selvaggia-craig-foster-9791259853929\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/intuizione-selvaggia-abbraccia-la-tua-anima-ancestrale-e-impara-dalla-natura-come-vivere-in-equilibrio-nel-mondo-di-oggi-craig-foster-harpercollins-italia-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/intuizione-selvaggia-abbraccia-la-tua-anima-ancestrale-e-impara-dalla-natura-come-vivere-in-equilibrio-nel-mondo-di-oggi-craig-foster-harpercollins-italia-1.jpg\",\"width\":500,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/intuizione-selvaggia-craig-foster-9791259853929\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"intuizione selvaggia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"19.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9791259853929\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"intuizione selvaggia - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/intuizione-selvaggia-craig-foster-9791259853929\/","og_locale":"en_US","og_type":"article","og_title":"intuizione selvaggia","og_description":"Subtitle: abbraccia la tua anima ancestrale e impara dalla natura come vivere in equilibrio nel mondo di oggiAuthor: craig fosterPublisher: harpercollins italiaISBN: 9791259853929","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/intuizione-selvaggia-craig-foster-9791259853929\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:22:21+00:00","og_image":[{"width":500,"height":750,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/intuizione-selvaggia-abbraccia-la-tua-anima-ancestrale-e-impara-dalla-natura-come-vivere-in-equilibrio-nel-mondo-di-oggi-craig-foster-harpercollins-italia-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;19,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/intuizione-selvaggia-craig-foster-9791259853929\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/intuizione-selvaggia-craig-foster-9791259853929\/","name":"intuizione selvaggia - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/intuizione-selvaggia-craig-foster-9791259853929\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/intuizione-selvaggia-craig-foster-9791259853929\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/intuizione-selvaggia-abbraccia-la-tua-anima-ancestrale-e-impara-dalla-natura-come-vivere-in-equilibrio-nel-mondo-di-oggi-craig-foster-harpercollins-italia-1.jpg","datePublished":"2024-11-05T17:47:04+00:00","dateModified":"2026-05-08T22:22:21+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/intuizione-selvaggia-craig-foster-9791259853929\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/intuizione-selvaggia-craig-foster-9791259853929\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/intuizione-selvaggia-craig-foster-9791259853929\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/intuizione-selvaggia-abbraccia-la-tua-anima-ancestrale-e-impara-dalla-natura-come-vivere-in-equilibrio-nel-mondo-di-oggi-craig-foster-harpercollins-italia-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/intuizione-selvaggia-abbraccia-la-tua-anima-ancestrale-e-impara-dalla-natura-come-vivere-in-equilibrio-nel-mondo-di-oggi-craig-foster-harpercollins-italia-1.jpg","width":500,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/intuizione-selvaggia-craig-foster-9791259853929\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"intuizione selvaggia"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"19.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9791259853929","product_condition":"new"},"df_price":19,"df_sale_price":"","df_regular_price":19,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/intuizione-selvaggia-abbraccia-la-tua-anima-ancestrale-e-impara-dalla-natura-come-vivere-in-equilibrio-nel-mondo-di-oggi-craig-foster-harpercollins-italia-1-200x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/139240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=139240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/139242"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=139240"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=139240"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=139240"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=139240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}