{"id":138723,"date":"2024-10-24T13:53:39","date_gmt":"2024-10-24T11:53:39","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/sebastiano-venier-nicolo-dal-grande-9788884747013\/"},"modified":"2026-07-11T00:36:38","modified_gmt":"2026-07-10T22:36:38","slug":"sebastiano-venier-nicolo-dal-grande-9788884747013","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/sebastiano-venier-nicolo-dal-grande-9788884747013\/","title":{"rendered":"sebastiano venier"},"content":{"rendered":"<p>La pi&ugrave; sanguinosa battaglia dell&#8217;Evo Moderno: cos&igrave; il grande storico Fernand Braudel ebbe a definire <strong>la cruenta giornata di Lepanto del 7 ottobre 1571<\/strong>, quando la flotta della Lega Santa distrusse quella ottomana. Una giornata destinata a restare nella storia che ebbe come conseguenza<strong> il crollo del mito dell&#8217;invincibilit&agrave; turca<\/strong>. Numerosi gli studi compiuti su quella grande giornata, molti meno quelli dedicati ai protagonisti che presero parte alla battaglia; tra questi spicca la figura di<strong> Sebastiano Venier<\/strong>, Capitano Generale della flotta veneziana e futuro Doge della Repubblica Serenissima. In questo nuovo studio, l&#8217;autore ricostruisce<strong> la vita e la carriera politica<\/strong> del famoso patrizio veneziano, dalla carriera avvocatizia alle reggenze di prestigiose citt&agrave; quali Candia, Brescia e Verona, sino ai cruenti e gloriosi giorni di guerra che lo avrebbero consacrato al soglio dogale e consegnato per sempre alla storia, in <strong>un&#8217;analisi che non trascura di delineare la societ&agrave; e la struttura politica veneziana<\/strong>, fornendo un&#8217;agile, ma profonda, descrizione di uno dei pi&ugrave; gloriosi Stati dell&#8217;Italia preunitaria.<\/p>\n<p>Edizione: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>vita e battaglie dell&#8217;eroe di lepanto<\/p>\n<p class=\"autore\"><span>Author: <\/span>nicol\u00f2 dal grande<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Il Cerchio iniziative editoriali<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788884747013<\/p>\n","protected":false},"featured_media":138721,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2803,3042],"product_tag":[],"class_list":{"0":"post-138723","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biography-and-memories","7":"product_cat-narrative-modern-era","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>sebastiano venier - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/sebastiano-venier-nicolo-dal-grande-9788884747013\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sebastiano venier\" \/>\n<meta property=\"og:description\" content=\"Subtitle: vita e battaglie dell&#039;eroe di lepantoAuthor: nicol\u00f2 dal grandePublisher: Il Cerchio iniziative editorialiISBN: 9788884747013\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/sebastiano-venier-nicolo-dal-grande-9788884747013\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T22:36:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sebastiano-venier-vita-e-battaglie-dell-eroe-di-lepanto-nicolo-dal-grande-il-cerchio-iniziative-editoriali.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;24,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sebastiano-venier-nicolo-dal-grande-9788884747013\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sebastiano-venier-nicolo-dal-grande-9788884747013\\\/\",\"name\":\"sebastiano venier - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sebastiano-venier-nicolo-dal-grande-9788884747013\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sebastiano-venier-nicolo-dal-grande-9788884747013\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sebastiano-venier-vita-e-battaglie-dell-eroe-di-lepanto-nicolo-dal-grande-il-cerchio-iniziative-editoriali.jpg\",\"datePublished\":\"2024-10-24T11:53:39+00:00\",\"dateModified\":\"2026-07-10T22:36:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sebastiano-venier-nicolo-dal-grande-9788884747013\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sebastiano-venier-nicolo-dal-grande-9788884747013\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sebastiano-venier-nicolo-dal-grande-9788884747013\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sebastiano-venier-vita-e-battaglie-dell-eroe-di-lepanto-nicolo-dal-grande-il-cerchio-iniziative-editoriali.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sebastiano-venier-vita-e-battaglie-dell-eroe-di-lepanto-nicolo-dal-grande-il-cerchio-iniziative-editoriali.jpg\",\"width\":500,\"height\":703},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sebastiano-venier-nicolo-dal-grande-9788884747013\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"sebastiano venier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"24.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788884747013\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"sebastiano venier - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/sebastiano-venier-nicolo-dal-grande-9788884747013\/","og_locale":"en_US","og_type":"article","og_title":"sebastiano venier","og_description":"Subtitle: vita e battaglie dell'eroe di lepantoAuthor: nicol\u00f2 dal grandePublisher: Il Cerchio iniziative editorialiISBN: 9788884747013","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/sebastiano-venier-nicolo-dal-grande-9788884747013\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T22:36:38+00:00","og_image":[{"width":500,"height":703,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sebastiano-venier-vita-e-battaglie-dell-eroe-di-lepanto-nicolo-dal-grande-il-cerchio-iniziative-editoriali.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;24,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sebastiano-venier-nicolo-dal-grande-9788884747013\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/sebastiano-venier-nicolo-dal-grande-9788884747013\/","name":"sebastiano venier - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sebastiano-venier-nicolo-dal-grande-9788884747013\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sebastiano-venier-nicolo-dal-grande-9788884747013\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sebastiano-venier-vita-e-battaglie-dell-eroe-di-lepanto-nicolo-dal-grande-il-cerchio-iniziative-editoriali.jpg","datePublished":"2024-10-24T11:53:39+00:00","dateModified":"2026-07-10T22:36:38+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sebastiano-venier-nicolo-dal-grande-9788884747013\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/sebastiano-venier-nicolo-dal-grande-9788884747013\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sebastiano-venier-nicolo-dal-grande-9788884747013\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sebastiano-venier-vita-e-battaglie-dell-eroe-di-lepanto-nicolo-dal-grande-il-cerchio-iniziative-editoriali.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sebastiano-venier-vita-e-battaglie-dell-eroe-di-lepanto-nicolo-dal-grande-il-cerchio-iniziative-editoriali.jpg","width":500,"height":703},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sebastiano-venier-nicolo-dal-grande-9788884747013\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"sebastiano venier"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"24.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788884747013","product_condition":"new"},"df_price":24,"df_sale_price":"","df_regular_price":24,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sebastiano-venier-vita-e-battaglie-dell-eroe-di-lepanto-nicolo-dal-grande-il-cerchio-iniziative-editoriali-213x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/138723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=138723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/138721"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=138723"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=138723"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=138723"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=138723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}