{"id":138434,"date":"2024-10-18T16:04:14","date_gmt":"2024-10-18T14:04:14","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\/"},"modified":"2026-07-11T00:37:03","modified_gmt":"2026-07-10T22:37:03","slug":"biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\/","title":{"rendered":"biglietto pieghevole con busta &#8211; origamo quilling &#8220;father and son&#8221;"},"content":{"rendered":"<p>Questo biglietto &egrave; stato <strong>realizzato a mano con l&rsquo;antica arte del Quilling (o Filigrana di Carta)<\/strong>. Tale tecnica era utilizzata dai monaci amanuensi durante il <strong>Rinascimento Italiano<\/strong> per impreziosire i codici miniati.<\/p>\n<p>A differenza del comune biglietto stampato, i Quilling Origamo sono <strong>piccole opere d&rsquo;arte<\/strong>, uniche e originali: un pensiero particolare per persone e occasioni speciali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 16&#215;16<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>origamo<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>8056736369753<\/p>\n","protected":false},"featured_media":138459,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2653],"product_tag":[],"class_list":{"0":"post-138434","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-greeting-cards-and-postcards","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>biglietto pieghevole con busta - origamo quilling &quot;father and son&quot; - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"biglietto pieghevole con busta - origamo quilling &quot;father and son&quot;\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 16x16Manufacturer: origamoISBN: 8056736369753\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T22:37:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"709\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;8,50\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\\\/\",\"name\":\"biglietto pieghevole con busta - origamo quilling \\\"father and son\\\" - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-2.jpg\",\"datePublished\":\"2024-10-18T14:04:14+00:00\",\"dateModified\":\"2026-07-10T22:37:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-2.jpg\",\"width\":709,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"biglietto pieghevole con busta &#8211; origamo quilling &#8220;father and son&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"8.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"8056736369753\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"biglietto pieghevole con busta - origamo quilling \"father and son\" - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\/","og_locale":"en_US","og_type":"article","og_title":"biglietto pieghevole con busta - origamo quilling \"father and son\"","og_description":"Subtitle: cm 16x16Manufacturer: origamoISBN: 8056736369753","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T22:37:03+00:00","og_image":[{"width":709,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;8,50","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\/","name":"biglietto pieghevole con busta - origamo quilling \"father and son\" - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-2.jpg","datePublished":"2024-10-18T14:04:14+00:00","dateModified":"2026-07-10T22:37:03+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-2.jpg","width":709,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-8056736369753\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"biglietto pieghevole con busta &#8211; origamo quilling &#8220;father and son&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"8.50","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"8056736369753","product_condition":"new"},"df_price":8.5,"df_sale_price":"","df_regular_price":8.5,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-pieghevole-con-busta-origamo-quilling-father-and-son-2-300x296.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/138434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=138434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/138459"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=138434"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=138434"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=138434"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=138434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}