{"id":138166,"date":"2024-10-16T13:06:28","date_gmt":"2024-10-16T11:06:28","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/centro-di-soccorso-marino-lego-friends-5702017415215\/"},"modified":"2026-07-11T00:37:50","modified_gmt":"2026-07-10T22:37:50","slug":"centro-di-soccorso-marino-lego-friends-5702017415215","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/centro-di-soccorso-marino-lego-friends-5702017415215\/","title":{"rendered":"centro di soccorso marino (lego friends)"},"content":{"rendered":"<p>I bambini che amano gli animali potranno inventare tante storie con un&rsquo;<strong>ambientazione marittima<\/strong> grazie al <em>Centro di soccorso marino<\/em>. Il set contiene <strong>3 mini-doll e 2 lontre marine, un cavalluccio marino e una tartaruga marina<\/strong>, oltre a tanti accessori per ispirare il gioco di finzione. I bambini possono usare lo <strong>scooter d&rsquo;acqua<\/strong> per arrivare al <strong>molo<\/strong>, entrare nel centro per <strong>pulire, fare le radiografie alle lontre e sfamarle<\/strong>. Possono quindi aiutarle a spostarsi nell&rsquo;<strong>area di riabilitazione<\/strong>. Quando le lontre son guarite, potranno tornare a nuotare nell&rsquo;oceano. Gli accessori includono <strong>un giubbotto di salvataggio, un biberon, un walkie-talkie, uno scrigno del tesoro, una macchina fotografica, un computer, un microscopio, una siringa e una macchina a raggi X<\/strong>.<\/p>\n<p><em>Aumenta il divertimento<\/em><br \/>I bambini possono tuffarsi in un&rsquo;avventura di costruzione facile e intuitiva con l&rsquo;<strong>app <em>Lego Builder<\/em><\/strong> che consente di <strong>ingrandire e ruotare i modelli 3D, salvare i set e tenere traccia dei progressi<\/strong>.<\/p>\n<p>Pezzi: 376<\/p>\n<p>Dimensioni: cm 20x19x23<\/p>\n<p>Et&agrave;: 7+<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"editore\"><span>Manufacturer: <\/span>lego<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>5702017415215<\/p>\n","protected":false},"featured_media":162094,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2931],"product_tag":[],"class_list":{"0":"post-138166","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-6-9-years-games","8":"first","9":"instock","10":"sale","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>centro di soccorso marino (lego friends) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/centro-di-soccorso-marino-lego-friends-5702017415215\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"centro di soccorso marino (lego friends)\" \/>\n<meta property=\"og:description\" content=\"Manufacturer: legoISBN: 5702017415215\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/centro-di-soccorso-marino-lego-friends-5702017415215\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T22:37:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/centro-di-soccorso-marino-lego-friends-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"933\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;42,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/centro-di-soccorso-marino-lego-friends-5702017415215\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/centro-di-soccorso-marino-lego-friends-5702017415215\\\/\",\"name\":\"centro di soccorso marino (lego friends) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/centro-di-soccorso-marino-lego-friends-5702017415215\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/centro-di-soccorso-marino-lego-friends-5702017415215\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/centro-di-soccorso-marino-lego-friends-1.jpg\",\"datePublished\":\"2024-10-16T11:06:28+00:00\",\"dateModified\":\"2026-07-10T22:37:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/centro-di-soccorso-marino-lego-friends-5702017415215\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/centro-di-soccorso-marino-lego-friends-5702017415215\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/centro-di-soccorso-marino-lego-friends-5702017415215\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/centro-di-soccorso-marino-lego-friends-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/centro-di-soccorso-marino-lego-friends-1.jpg\",\"width\":933,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/centro-di-soccorso-marino-lego-friends-5702017415215\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"centro di soccorso marino (lego friends)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"42.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"5702017415215\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"centro di soccorso marino (lego friends) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/centro-di-soccorso-marino-lego-friends-5702017415215\/","og_locale":"en_US","og_type":"article","og_title":"centro di soccorso marino (lego friends)","og_description":"Manufacturer: legoISBN: 5702017415215","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/centro-di-soccorso-marino-lego-friends-5702017415215\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T22:37:50+00:00","og_image":[{"width":933,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/centro-di-soccorso-marino-lego-friends-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;42,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/centro-di-soccorso-marino-lego-friends-5702017415215\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/centro-di-soccorso-marino-lego-friends-5702017415215\/","name":"centro di soccorso marino (lego friends) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/centro-di-soccorso-marino-lego-friends-5702017415215\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/centro-di-soccorso-marino-lego-friends-5702017415215\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/centro-di-soccorso-marino-lego-friends-1.jpg","datePublished":"2024-10-16T11:06:28+00:00","dateModified":"2026-07-10T22:37:50+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/centro-di-soccorso-marino-lego-friends-5702017415215\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/centro-di-soccorso-marino-lego-friends-5702017415215\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/centro-di-soccorso-marino-lego-friends-5702017415215\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/centro-di-soccorso-marino-lego-friends-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/centro-di-soccorso-marino-lego-friends-1.jpg","width":933,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/centro-di-soccorso-marino-lego-friends-5702017415215\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"centro di soccorso marino (lego friends)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"42.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"5702017415215","product_condition":"new"},"df_price":42,"df_sale_price":42,"df_regular_price":61,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/centro-di-soccorso-marino-lego-friends-1-300x225.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/138166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=138166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/162094"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=138166"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=138166"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=138166"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=138166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}