{"id":137731,"date":"2024-10-04T12:10:45","date_gmt":"2024-10-04T10:10:45","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\/"},"modified":"2026-07-11T00:38:23","modified_gmt":"2026-07-10T22:38:23","slug":"agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\/","title":{"rendered":"agenda settimanale blackie 2025"},"content":{"rendered":"<p>Un&#8217;agenda per prenderti cura del tuo tempo. Con poster calendario!&nbsp;<\/p>\n<p><strong>La cosa migliore che possiamo fare con il nostro tempo &egrave; prendercene cura<\/strong>. Apprezzare ogni buon momento, non dare nulla per scontato, <strong>essere consapevoli delle ore felici e abbandonarci al piacere quando il piacere ci trova<\/strong>. Ovviamente, &egrave; molto pi&ugrave; facile a dirsi che a farsi, ma mentre scopriamo il modo, possiamo trascorrere quest&#8217;anno insieme. <strong>Davanti ai nostri occhi si apre un nuovo anno<\/strong>. Andiamogli incontro.<\/p>\n<ul>\n<li>Vista settimanale<\/li>\n<li>Tanto spazio per organizzare le tue attivit&agrave;<\/li>\n<li>Citazioni e frasi memorabili<\/li>\n<li>Liste per annotare ricette, drink, posti del cuore<\/li>\n<li>Libri e film imperdibili<\/li>\n<li>Calendario di frutta e verdura di stagione<\/li>\n<li>200+ illustrazioni.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 14&#215;21<\/p>\n<p class=\"autore\"><span>Author: <\/span>daniel lopez valle &#8211; illustrazioni di julio fuentes<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>Blackie Edizioni<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788831321846<\/p>\n","protected":false},"featured_media":142066,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2844],"product_tag":[],"class_list":{"0":"post-137731","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-agendas","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>agenda settimanale blackie 2025 - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"agenda settimanale blackie 2025\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 14x21Author: daniel lopez valle - illustrazioni di julio fuentesManufacturer: Blackie EdizioniISBN: 9788831321846\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T22:38:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/agenda-settimanale-blackie-2025-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"525\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;18,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\\\/\",\"name\":\"agenda settimanale blackie 2025 - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/agenda-settimanale-blackie-2025-1.jpg\",\"datePublished\":\"2024-10-04T10:10:45+00:00\",\"dateModified\":\"2026-07-10T22:38:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/agenda-settimanale-blackie-2025-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/agenda-settimanale-blackie-2025-1.jpg\",\"width\":525,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"agenda settimanale blackie 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"18.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788831321846\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"agenda settimanale blackie 2025 - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\/","og_locale":"en_US","og_type":"article","og_title":"agenda settimanale blackie 2025","og_description":"Subtitle: cm 14x21Author: daniel lopez valle - illustrazioni di julio fuentesManufacturer: Blackie EdizioniISBN: 9788831321846","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T22:38:23+00:00","og_image":[{"width":525,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/agenda-settimanale-blackie-2025-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;18,90","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\/","name":"agenda settimanale blackie 2025 - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/agenda-settimanale-blackie-2025-1.jpg","datePublished":"2024-10-04T10:10:45+00:00","dateModified":"2026-07-10T22:38:23+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/agenda-settimanale-blackie-2025-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/agenda-settimanale-blackie-2025-1.jpg","width":525,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/agenda-settimanale-blackie-2025-daniel-lopez-valle-illustrazioni-di-julio-fuentes-9788831321846\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"agenda settimanale blackie 2025"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"18.90","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"9788831321846","product_condition":"new"},"df_price":18.9,"df_sale_price":"","df_regular_price":18.9,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/agenda-settimanale-blackie-2025-1-225x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/137731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=137731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/142066"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=137731"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=137731"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=137731"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=137731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}