{"id":136889,"date":"2024-09-18T16:01:42","date_gmt":"2024-09-18T14:01:42","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\/"},"modified":"2026-05-09T00:24:57","modified_gmt":"2026-05-08T22:24:57","slug":"profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\/","title":{"rendered":"profondo come il mare"},"content":{"rendered":"<p>Il settimo numero della collana &#8220;<em>Quaderni di Fotografia<\/em>&#8221; &egrave; anche il <strong>catalogo della mostra presso Palazzo del Duca di Senigallia <\/strong>(28 giugno &#8211; 13 ottobre 2024) in cui vengono esposti circa <strong>80 scatti, tutti a tema marino, dalla collezione Rita e Riccardo Marone<\/strong>.<\/p>\n<p>Fra gli artisti in mostra: <em>Marina Abramovic, Henri Cartier-Bresson, Gianni Berengo Gardin, Giuseppe Cavalli, Luigi Ghirri, Mimmo e Francesco Jodice, Armin Linke, Robert Mapplethorpe, Pepi Merisio, Massimo Siragusa, Spencer Tunick, Michele Zaza, Helmut Newton, Martin Parr, Gordon Parks, Mario Giacomelli, Nino Migliori<\/em>.<\/p>\n<p>Edizione: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>il tema marino tra collezionismo e iconografia<\/p>\n<p class=\"autore\"><span>Author: <\/span>a cura di angela madesani<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>nomos edizioni<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9791259581952<\/p>\n","protected":false},"featured_media":136881,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2646],"product_tag":[],"class_list":{"0":"post-136889","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-world-picture-books-tourism","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>profondo come il mare - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"profondo come il mare\" \/>\n<meta property=\"og:description\" content=\"Subtitle: il tema marino tra collezionismo e iconografiaAuthor: a cura di angela madesaniPublisher: nomos edizioniISBN: 9791259581952\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:24:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/profondo-come-il-mare-nomos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;14,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\\\/\",\"name\":\"profondo come il mare - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/profondo-come-il-mare-nomos.jpg\",\"datePublished\":\"2024-09-18T14:01:42+00:00\",\"dateModified\":\"2026-05-08T22:24:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/profondo-come-il-mare-nomos.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/profondo-come-il-mare-nomos.jpg\",\"width\":500,\"height\":718},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"profondo come il mare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"14.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9791259581952\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"profondo come il mare - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\/","og_locale":"en_US","og_type":"article","og_title":"profondo come il mare","og_description":"Subtitle: il tema marino tra collezionismo e iconografiaAuthor: a cura di angela madesaniPublisher: nomos edizioniISBN: 9791259581952","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:24:57+00:00","og_image":[{"width":500,"height":718,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/profondo-come-il-mare-nomos.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;14,90","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\/","name":"profondo come il mare - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/profondo-come-il-mare-nomos.jpg","datePublished":"2024-09-18T14:01:42+00:00","dateModified":"2026-05-08T22:24:57+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/profondo-come-il-mare-nomos.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/profondo-come-il-mare-nomos.jpg","width":500,"height":718},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/profondo-come-il-mare-a-cura-di-angela-madesani-9791259581952\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"profondo come il mare"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"14.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9791259581952","product_condition":"new"},"df_price":14.9,"df_sale_price":"","df_regular_price":14.9,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/profondo-come-il-mare-nomos-209x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/136889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=136889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/136881"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=136889"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=136889"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=136889"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=136889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}