{"id":135948,"date":"2024-08-30T13:12:29","date_gmt":"2024-08-30T11:12:29","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\/"},"modified":"2026-05-09T00:25:31","modified_gmt":"2026-05-08T22:25:31","slug":"squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\/","title":{"rendered":"squali (libri con adesivi)"},"content":{"rendered":"<p>Dagli squali martello agli enormi megalodonti, <strong>in questo libro con adesivi ci sono tutte le specie del pi&ugrave; famoso predatore del pianeta!<\/strong><\/p>\n<p>Grazie alle <strong>centinaia di adesivi<\/strong> inclusi e alle <strong>informazioni che completano le illustrazioni<\/strong>, questo libro garantisce ore di divertimento istruttivo.<\/p>\n<p>Et&agrave;: <strong>5+<\/strong><\/p>\n<p>Edizione: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>alice james &#8211; illustrazioni di amanda shufflebotham<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>usborne publishing (italia)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9781835401996<\/p>\n","protected":false},"featured_media":135952,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2616],"product_tag":[],"class_list":{"0":"post-135948","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-activity-books","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>squali (libri con adesivi) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"squali (libri con adesivi)\" \/>\n<meta property=\"og:description\" content=\"Author: alice james - illustrazioni di amanda shufflebothamPublisher: usborne publishing (italia)ISBN: 9781835401996\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:25:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/squali-libri-con-adesivi-james-shufflebotham-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"545\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;8,50\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\\\/\",\"name\":\"squali (libri con adesivi) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/squali-libri-con-adesivi-james-shufflebotham-2.jpg\",\"datePublished\":\"2024-08-30T11:12:29+00:00\",\"dateModified\":\"2026-05-08T22:25:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/squali-libri-con-adesivi-james-shufflebotham-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/squali-libri-con-adesivi-james-shufflebotham-2.jpg\",\"width\":545,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"squali (libri con adesivi)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"8.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9781835401996\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"squali (libri con adesivi) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\/","og_locale":"en_US","og_type":"article","og_title":"squali (libri con adesivi)","og_description":"Author: alice james - illustrazioni di amanda shufflebothamPublisher: usborne publishing (italia)ISBN: 9781835401996","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:25:31+00:00","og_image":[{"width":545,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/squali-libri-con-adesivi-james-shufflebotham-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;8,50","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\/","name":"squali (libri con adesivi) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/squali-libri-con-adesivi-james-shufflebotham-2.jpg","datePublished":"2024-08-30T11:12:29+00:00","dateModified":"2026-05-08T22:25:31+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/squali-libri-con-adesivi-james-shufflebotham-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/squali-libri-con-adesivi-james-shufflebotham-2.jpg","width":545,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/squali-libri-con-adesivi-alice-james-illustrazioni-di-amanda-shufflebotham-9781835401996\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"squali (libri con adesivi)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"8.50","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9781835401996","product_condition":"new"},"df_price":8.5,"df_sale_price":"","df_regular_price":8.5,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/squali-libri-con-adesivi-james-shufflebotham-2-234x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/135948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=135948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/135952"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=135948"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=135948"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=135948"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=135948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}