{"id":133871,"date":"2024-08-07T12:57:39","date_gmt":"2024-08-07T10:57:39","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\/"},"modified":"2026-05-09T00:25:49","modified_gmt":"2026-05-08T22:25:49","slug":"sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\/","title":{"rendered":"sea creatures: shark (pop-ups)"},"content":{"rendered":"<p><em>Sea Creatures<\/em> is a range of six <strong>pop-up cards<\/strong>. All are suitable for collecting, framing and make great gifts and they all come with an envelope.<\/p>\n<p><strong>Printed on paper from known and responsible sources.<\/strong><\/p>\n<p>Size: 15&#215;15 cm<\/p>\n<p>Envelope: 16&#215;16 cm<\/p>\n<p>Edition: 2015<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>maike biederstadt<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>2totango<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>5060294291480<\/p>\n","protected":false},"featured_media":148217,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2653],"product_tag":[],"class_list":{"0":"post-133871","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-greeting-cards-and-postcards","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>sea creatures: shark (pop-ups) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sea creatures: shark (pop-ups)\" \/>\n<meta property=\"og:description\" content=\"Author: maike biederstadtManufacturer: 2totangoISBN: 5060294291480\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:25:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sea-creatures-shark-pop-ups-maike-biederstadt-2totango-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"698\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;9,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\\\/\",\"name\":\"sea creatures: shark (pop-ups) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sea-creatures-shark-pop-ups-maike-biederstadt-2totango-2.jpg\",\"datePublished\":\"2024-08-07T10:57:39+00:00\",\"dateModified\":\"2026-05-08T22:25:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sea-creatures-shark-pop-ups-maike-biederstadt-2totango-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sea-creatures-shark-pop-ups-maike-biederstadt-2totango-2.jpg\",\"width\":698,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"sea creatures: shark (pop-ups)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"9.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"5060294291480\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"sea creatures: shark (pop-ups) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\/","og_locale":"en_US","og_type":"article","og_title":"sea creatures: shark (pop-ups)","og_description":"Author: maike biederstadtManufacturer: 2totangoISBN: 5060294291480","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:25:49+00:00","og_image":[{"width":698,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sea-creatures-shark-pop-ups-maike-biederstadt-2totango-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;9,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\/","name":"sea creatures: shark (pop-ups) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sea-creatures-shark-pop-ups-maike-biederstadt-2totango-2.jpg","datePublished":"2024-08-07T10:57:39+00:00","dateModified":"2026-05-08T22:25:49+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sea-creatures-shark-pop-ups-maike-biederstadt-2totango-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sea-creatures-shark-pop-ups-maike-biederstadt-2totango-2.jpg","width":698,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sea-creatures-shark-pop-ups-maike-biederstadt-5060294291480\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"sea creatures: shark (pop-ups)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"9.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"5060294291480","product_condition":"new"},"df_price":9,"df_sale_price":"","df_regular_price":9,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sea-creatures-shark-pop-ups-maike-biederstadt-2totango-2-300x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/133871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=133871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/148217"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=133871"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=133871"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=133871"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=133871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}