{"id":129581,"date":"2024-07-25T17:22:04","date_gmt":"2024-07-25T15:22:04","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/antartide-1912-davide-morganti-9788897073871\/"},"modified":"2026-05-09T00:26:01","modified_gmt":"2026-05-08T22:26:01","slug":"antartide-1912-davide-morganti-9788897073871","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/antartide-1912-davide-morganti-9788897073871\/","title":{"rendered":"antartide 1912"},"content":{"rendered":"<p><strong>Casimiro Boboski, nel suo viaggio intorno al mondo, arriva in Antartide. Incontra lo spettro di <em>Lawrence Oates<\/em><\/strong>, un esploratore della spedizione al Polo Sud di <em>Robert Falcon Scott<\/em>, e ascolta la sua storia. Oates, malato e ferito alle gambe, si rende conto di essere un peso e durante una tempesta di neve, a 40 gradi sottozero, in preda alla febbre, infila a fatica le sue scarpe e dice: &ldquo;<em>I am just going outside and may be some time<\/em>&rdquo;. Magari ci resto un po&rsquo;. Il suo corpo non venne mai trovato. Aveva solo 32 anni.<\/p>\n<p><strong><em>Davide Morganti<\/em>, con questa cartolina vecchia di 100 anni, ci porta al Polo Sud e ci racconta la storia di un uomo diventato leggenda.<\/strong><\/p>\n<p>Questo titolo fa parte della collana <em>Le Cartoline<\/em>: frammenti di storia mezzo posta &#8211; stop &#8211; raccontiamo anni e citt&agrave; dentro cartoline &#8211; stop &#8211; massima urgenza &#8211; stop &#8211; per lettori sempre in viaggio &#8211; stop &#8211; il mondo sotto un francobollo<\/p>\n<p>Edizione: 2022<\/p>\n<p><strong>La Coppola Editore &egrave; una casa editrice indipendente siculo-campana<\/strong>. &Egrave; una casa editrice Terrona, orgogliosamente terrona. Un&rsquo;impresa fondata da Salvatore Coppola a Trapani nel 1984, con uno sguardo attento al territorio, agli scrittori contemporanei e ai temi della legalit&agrave;. Lontana dalle mode editoriali e dai grossi circuiti &egrave; un&rsquo;impresa distintasi in Sicilia e non solo, per la sua voce fuori dal coro. Particolarmente attenta all&rsquo;ambiente pubblica libri su carta riciclata certificata e con inchiostri non inquinanti. Si distingue per le sue autoproduzioni, libri fatti a mano attraverso una legatoria sociale aperta al territorio. Dopo la morte di Salvatore Coppola nel 2013, la casa editrice viene rilevata nel 2016 da Rosario Esposito La Rossa e Maddalena Stornaiuolo, e trasferita da Trapani a Scampia (Napoli).<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>magari ci resto un po&#8217; (le cartoline)<\/p>\n<p class=\"autore\"><span>Author: <\/span>davide morganti<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>coppola editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788897073871<\/p>\n","protected":false},"featured_media":129579,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3011,2811],"product_tag":[],"class_list":{"0":"post-129581","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-the-conquest-of-the-poles","7":"product_cat-short-stories","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>antartide 1912 - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/antartide-1912-davide-morganti-9788897073871\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"antartide 1912\" \/>\n<meta property=\"og:description\" content=\"Subtitle: magari ci resto un po&#039; (le cartoline)Author: davide morgantiPublisher: coppola editoreISBN: 9788897073871\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/antartide-1912-davide-morganti-9788897073871\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:26:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/antartide-1912-davide-morganti-coppola-editore.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;10,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/antartide-1912-davide-morganti-9788897073871\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/antartide-1912-davide-morganti-9788897073871\\\/\",\"name\":\"antartide 1912 - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/antartide-1912-davide-morganti-9788897073871\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/antartide-1912-davide-morganti-9788897073871\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/antartide-1912-davide-morganti-coppola-editore.jpg\",\"datePublished\":\"2024-07-25T15:22:04+00:00\",\"dateModified\":\"2026-05-08T22:26:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/antartide-1912-davide-morganti-9788897073871\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/antartide-1912-davide-morganti-9788897073871\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/antartide-1912-davide-morganti-9788897073871\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/antartide-1912-davide-morganti-coppola-editore.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/antartide-1912-davide-morganti-coppola-editore.jpg\",\"width\":1000,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/antartide-1912-davide-morganti-9788897073871\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"antartide 1912\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"10.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788897073871\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"antartide 1912 - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/antartide-1912-davide-morganti-9788897073871\/","og_locale":"en_US","og_type":"article","og_title":"antartide 1912","og_description":"Subtitle: magari ci resto un po' (le cartoline)Author: davide morgantiPublisher: coppola editoreISBN: 9788897073871","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/antartide-1912-davide-morganti-9788897073871\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:26:01+00:00","og_image":[{"width":1000,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/antartide-1912-davide-morganti-coppola-editore.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;10,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/antartide-1912-davide-morganti-9788897073871\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/antartide-1912-davide-morganti-9788897073871\/","name":"antartide 1912 - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/antartide-1912-davide-morganti-9788897073871\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/antartide-1912-davide-morganti-9788897073871\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/antartide-1912-davide-morganti-coppola-editore.jpg","datePublished":"2024-07-25T15:22:04+00:00","dateModified":"2026-05-08T22:26:01+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/antartide-1912-davide-morganti-9788897073871\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/antartide-1912-davide-morganti-9788897073871\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/antartide-1912-davide-morganti-9788897073871\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/antartide-1912-davide-morganti-coppola-editore.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/antartide-1912-davide-morganti-coppola-editore.jpg","width":1000,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/antartide-1912-davide-morganti-9788897073871\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"antartide 1912"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"10.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788897073871","product_condition":"new"},"df_price":10,"df_sale_price":"","df_regular_price":10,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/antartide-1912-davide-morganti-coppola-editore-300x210.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/129581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=129581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/129579"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=129581"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=129581"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=129581"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=129581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}