{"id":122745,"date":"2024-06-28T16:23:09","date_gmt":"2024-06-28T14:23:09","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/fari-del-nord-torben-ratzlaff-8033609532773\/"},"modified":"2026-07-11T00:42:57","modified_gmt":"2026-07-10T22:42:57","slug":"fari-del-nord-torben-ratzlaff-8033609532773","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/fari-del-nord-torben-ratzlaff-8033609532773\/","title":{"rendered":"fari del nord"},"content":{"rendered":"<p><strong>Levate gli ormeggi e solcate le acque!<\/strong><\/p>\n<p><strong>Navigate tra le insenature per creare una mappa<\/strong> delle isole, dei fari, delle boe di segnalazione, delle pale eoliche e di molto altro.&nbsp;<strong><em>Fari del Nord&nbsp;<\/em>&egrave; un gioco cooperativo <\/strong>rilassante, profondo e ricco di sfide, in cui tu e il tuo gruppo di amici dovrete esplorare la costa, una tessera alla volta.&nbsp;Siete <strong>capitani della Guardia Costiera <\/strong>e avete il compito di assicurarvi che le coste del Mare del Nord siano sempre sicure. Lavorate insieme per esplorare le acque e per ispezionare fari e boe di vitale importanza. Agite con efficienza, poich&eacute; il mare &egrave; vasto e il tempo scarseggia! <strong>Muovete la vostra nave, piazzate le tessere e collaborate con i vostri compagni<\/strong> capitani per ottenere una promozione e l&rsquo;ammirazione di tutti gli abitanti della costa.<\/p>\n<p><strong>Nel vostro turno potete:<\/strong><\/p>\n<ul>\n<li><strong>piazzare una tessera<\/strong> (fino a un massimo di 2 o 3 a seconda del numero di giocatori) rispettando le regole di piazzamento (adiacente alla tessera con la vostra nave, orientamento corretto e corrispondenza). <strong>Poi, spostate la nave<\/strong> lungo il mare sulla tessera appena posizionata;<\/li>\n<li><strong>muovere la nave<\/strong> utilizzando i gettoni movimento;<\/li>\n<li><strong>scambiare una tessera<\/strong> con una di un compagno.<\/li>\n<\/ul>\n<p><strong>La partita termina quando finiscono le tessere<\/strong>. Si ottengono punti per le tessere esplorate. Maggiori punti si ottengono se le tessere contengono fari o boe.<\/p>\n<p>Contenuto:<\/p>\n<ul>\n<li><strong>64 tessere quadrate<\/strong> (con una mini espansione con ulteriori tessere da giocare: le pale eoliche e i moli)<\/li>\n<li style=\"font-weight: bold\"><strong>9 tessere tonde<\/strong><\/li>\n<li><strong>4 navi <\/strong>in legno dipinte<\/li>\n<li><strong>4 carte riassuntive <\/strong>(mm 70&#215;20)<\/li>\n<\/ul>\n<p>Et&agrave;: 8+<\/p>\n<p>Durata: 30 minuti<\/p>\n<p>Giocatori: 1-4<\/p>\n<p>Edizione: 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>torben ratzlaff<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>ghenos games<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>8033609532773<\/p>\n","protected":false},"featured_media":147630,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2931],"product_tag":[],"class_list":{"0":"post-122745","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-6-9-years-games","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>fari del nord - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/fari-del-nord-torben-ratzlaff-8033609532773\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"fari del nord\" \/>\n<meta property=\"og:description\" content=\"Author: torben ratzlaffManufacturer: ghenos gamesISBN: 8033609532773\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/fari-del-nord-torben-ratzlaff-8033609532773\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T22:42:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/fari-del-nord-torben-ratzlaff-pandasaurus-games-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"954\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;22,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/fari-del-nord-torben-ratzlaff-8033609532773\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/fari-del-nord-torben-ratzlaff-8033609532773\\\/\",\"name\":\"fari del nord - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/fari-del-nord-torben-ratzlaff-8033609532773\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/fari-del-nord-torben-ratzlaff-8033609532773\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/fari-del-nord-torben-ratzlaff-pandasaurus-games-2.jpg\",\"datePublished\":\"2024-06-28T14:23:09+00:00\",\"dateModified\":\"2026-07-10T22:42:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/fari-del-nord-torben-ratzlaff-8033609532773\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/fari-del-nord-torben-ratzlaff-8033609532773\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/fari-del-nord-torben-ratzlaff-8033609532773\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/fari-del-nord-torben-ratzlaff-pandasaurus-games-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/fari-del-nord-torben-ratzlaff-pandasaurus-games-2.jpg\",\"width\":500,\"height\":954},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/fari-del-nord-torben-ratzlaff-8033609532773\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"fari del nord\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"22.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"8033609532773\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"fari del nord - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/fari-del-nord-torben-ratzlaff-8033609532773\/","og_locale":"en_US","og_type":"article","og_title":"fari del nord","og_description":"Author: torben ratzlaffManufacturer: ghenos gamesISBN: 8033609532773","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/fari-del-nord-torben-ratzlaff-8033609532773\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T22:42:57+00:00","og_image":[{"width":500,"height":954,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/fari-del-nord-torben-ratzlaff-pandasaurus-games-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;22,90","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/fari-del-nord-torben-ratzlaff-8033609532773\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/fari-del-nord-torben-ratzlaff-8033609532773\/","name":"fari del nord - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/fari-del-nord-torben-ratzlaff-8033609532773\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/fari-del-nord-torben-ratzlaff-8033609532773\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/fari-del-nord-torben-ratzlaff-pandasaurus-games-2.jpg","datePublished":"2024-06-28T14:23:09+00:00","dateModified":"2026-07-10T22:42:57+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/fari-del-nord-torben-ratzlaff-8033609532773\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/fari-del-nord-torben-ratzlaff-8033609532773\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/fari-del-nord-torben-ratzlaff-8033609532773\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/fari-del-nord-torben-ratzlaff-pandasaurus-games-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/fari-del-nord-torben-ratzlaff-pandasaurus-games-2.jpg","width":500,"height":954},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/fari-del-nord-torben-ratzlaff-8033609532773\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"fari del nord"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"22.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"8033609532773","product_condition":"new"},"df_price":22.9,"df_sale_price":"","df_regular_price":22.9,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/fari-del-nord-torben-ratzlaff-pandasaurus-games-2-157x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/122745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=122745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/147630"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=122745"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=122745"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=122745"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=122745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}