{"id":122717,"date":"2024-06-28T14:52:45","date_gmt":"2024-06-28T12:52:45","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/yacht-design-spring-2024-aa-vv-ldm1719579164\/"},"modified":"2026-07-11T00:43:03","modified_gmt":"2026-07-10T22:43:03","slug":"yacht-design-spring-2024-aa-vv-ldm1719579164","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/yacht-design-spring-2024-aa-vv-ldm1719579164\/","title":{"rendered":"Yacht Design &#8211; Spring 2024"},"content":{"rendered":"<p>Yacht Design was born from the experience gained by Boat Show Television as a leader in the production of content dedicated to international boating. An experience that has led The Boat Show to be a national and international point of reference on all the main video broadcast, OTT and social channels.<\/p>\n<p>Yacht Design talks about sailing by telling circular stories of passion for the sea, with a focus on design, the fundamental driving force of the sector. Design in the form of art, shapes, environment, materials, technology, innovation, large international fairs, culture, literature, economy, sector leaders, destinations, regattas, major navigations.<\/p>\n<p>A way of communicating built for an international audience, with a system logic that links paper, video and social identity.<\/p>\n<p>In this issue:<\/p>\n<ul>\n<li><em>Editorial &#8220;The Auld Mug is Back&#8221;<\/em> by Antonio Vettese<\/li>\n<li><em>Shooting the Depths<\/em> by Cristina Mittermeier<\/li>\n<li><em>Our Timeless Passion &#8211; Hoek Design<\/em> by Gigi Radice<\/li>\n<li style=\"font-style: italic\"><em>Superleggera<\/em><\/li>\n<li><em>Misa Poggi&#8217;s Architecture<\/em> by Marta Rovatti Studihrad<\/li>\n<li><em>The Wally Way<\/em> by Antonio Vettese<\/li>\n<li><em>My American Dream &#8211; Patrizio Bertelli<\/em> by Antonio Vettese<\/li>\n<li style=\"font-style: italic\"><em>Fusion<\/em><\/li>\n<li style=\"font-style: italic\"><em>Gelliceaux<\/em><\/li>\n<li style=\"font-style: italic\"><em>Sparta<\/em><\/li>\n<li><em>Y9 Pilot House<\/em><\/li>\n<li><em>Transavantg\/Art &#8211; Mimmo Paladino<\/em> by Francesca Molteni<\/li>\n<li><em>AI Gets on Board&nbsp;<\/em>by Arianna Bionda and Massimo Piccioni<\/li>\n<li><em>Hong Kong by the Sea<\/em> by Guy Nowell and Suzy Rayment<\/li>\n<li><em>The Perfect Shape&nbsp;<\/em>by Gigi Radice<\/li>\n<li><em>The Wizard of the Hulls &#8211; Brunello Acampora<\/em> by Francesca Albini<\/li>\n<li><em>Final Cut<\/em><\/li>\n<li><em>The 7th Italian Design Conference<\/em><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>Maggio 2024 &#8211; Anno 3_ n\u00b05<\/p>\n<p class=\"autore\"><span>Author: <\/span>AA.VV.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Boat Show Television<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1719579164<\/p>\n","protected":false},"featured_media":166026,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2593],"product_tag":[],"class_list":{"0":"post-122717","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-magazines","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Yacht Design - Spring 2024 - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/yacht-design-spring-2024-aa-vv-ldm1719579164\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yacht Design - Spring 2024\" \/>\n<meta property=\"og:description\" content=\"Subtitle: Maggio 2024 - Anno 3_ n\u00b05Author: AA.VV.Publisher: Boat Show TelevisionISBN: LDM1719579164\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/yacht-design-spring-2024-aa-vv-ldm1719579164\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T22:43:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/yacht-design-spring-2024-maggio-2024-anno-3-n-5-boat-show-television-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"517\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;20,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/yacht-design-spring-2024-aa-vv-ldm1719579164\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/yacht-design-spring-2024-aa-vv-ldm1719579164\\\/\",\"name\":\"Yacht Design - Spring 2024 - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/yacht-design-spring-2024-aa-vv-ldm1719579164\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/yacht-design-spring-2024-aa-vv-ldm1719579164\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/yacht-design-spring-2024-maggio-2024-anno-3-n-5-boat-show-television-1.jpg\",\"datePublished\":\"2024-06-28T12:52:45+00:00\",\"dateModified\":\"2026-07-10T22:43:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/yacht-design-spring-2024-aa-vv-ldm1719579164\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/yacht-design-spring-2024-aa-vv-ldm1719579164\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/yacht-design-spring-2024-aa-vv-ldm1719579164\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/yacht-design-spring-2024-maggio-2024-anno-3-n-5-boat-show-television-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/yacht-design-spring-2024-maggio-2024-anno-3-n-5-boat-show-television-1.jpg\",\"width\":517,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/yacht-design-spring-2024-aa-vv-ldm1719579164\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Yacht Design &#8211; Spring 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"20.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1719579164\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Yacht Design - Spring 2024 - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/yacht-design-spring-2024-aa-vv-ldm1719579164\/","og_locale":"en_US","og_type":"article","og_title":"Yacht Design - Spring 2024","og_description":"Subtitle: Maggio 2024 - Anno 3_ n\u00b05Author: AA.VV.Publisher: Boat Show TelevisionISBN: LDM1719579164","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/yacht-design-spring-2024-aa-vv-ldm1719579164\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T22:43:03+00:00","og_image":[{"width":517,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/yacht-design-spring-2024-maggio-2024-anno-3-n-5-boat-show-television-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;20,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/yacht-design-spring-2024-aa-vv-ldm1719579164\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/yacht-design-spring-2024-aa-vv-ldm1719579164\/","name":"Yacht Design - Spring 2024 - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/yacht-design-spring-2024-aa-vv-ldm1719579164\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/yacht-design-spring-2024-aa-vv-ldm1719579164\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/yacht-design-spring-2024-maggio-2024-anno-3-n-5-boat-show-television-1.jpg","datePublished":"2024-06-28T12:52:45+00:00","dateModified":"2026-07-10T22:43:03+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/yacht-design-spring-2024-aa-vv-ldm1719579164\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/yacht-design-spring-2024-aa-vv-ldm1719579164\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/yacht-design-spring-2024-aa-vv-ldm1719579164\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/yacht-design-spring-2024-maggio-2024-anno-3-n-5-boat-show-television-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/yacht-design-spring-2024-maggio-2024-anno-3-n-5-boat-show-television-1.jpg","width":517,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/yacht-design-spring-2024-aa-vv-ldm1719579164\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Yacht Design &#8211; Spring 2024"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"20.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"LDM1719579164","product_condition":"new"},"df_price":20,"df_sale_price":"","df_regular_price":20,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/yacht-design-spring-2024-maggio-2024-anno-3-n-5-boat-show-television-1-222x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/122717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=122717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/166026"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=122717"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=122717"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=122717"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=122717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}