{"id":121624,"date":"2023-10-04T13:19:14","date_gmt":"2023-10-04T11:19:14","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\/"},"modified":"2026-05-09T00:38:43","modified_gmt":"2026-05-08T22:38:43","slug":"islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\/","title":{"rendered":"islanda (piccolo atlante edonista)"},"content":{"rendered":"<p>L&rsquo;<strong>eterna lotta tra il ghiaccio e il fuoco<\/strong>, Reykjav&iacute;k, il cuore pulsante d&rsquo;Islanda, la gastronomia nordica, fra innovazione e tradizione, gli eroi delle antiche saghe e la loro eredit&agrave;, l&rsquo;epopea dei pescatori in mezzo alle tempeste polari, la magia delle aurore boreali&#8230;<\/p>\n<p><strong>Partire per l&#8217;Islanda &egrave; un po&#8217; come andare sulla luna<\/strong>, tra paesaggi punteggiati da fumarole, geyser, ghiacciai, vulcani, spettacolari cascate, pozze di fango ribollente, colorazioni sgargianti uniche al mondo&#8230; Un&#8217;isola stupefacente, che affascina chiunque sia in cerca di <strong>un&#8217;altra dimensione<\/strong>.<\/p>\n<p>I <strong><em>Piccoli Atlanti Edonisti<\/em><\/strong> appartengono a <strong>una collana di guide insolite per godersi il viaggio e perdere la rotta<\/strong>:<\/p>\n<ul>\n<li>mappe delle regioni per individuare i principali punti di interesse<\/li>\n<li>sezioni tematiche per conoscere e capire il paese<\/li>\n<li>schede riassuntive delle mete pi&ugrave; iconiche<\/li>\n<li>itinerari ed escursioni per scoprire ogni regione in modo originale<\/li>\n<\/ul>\n<p>Edizione: 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>bertrand jouanne &#8211; gunnar freyr<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>L&#8217;ippocampo<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788867227617<\/p>\n","protected":false},"featured_media":135160,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2644,3106],"product_tag":[],"class_list":{"0":"post-121624","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-europe-and-mediterranean-sea-picture-books-tourism","7":"product_cat-everything-else-europe-and-mediterranean-sea-tourist-guides","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>islanda (piccolo atlante edonista) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"islanda (piccolo atlante edonista)\" \/>\n<meta property=\"og:description\" content=\"Author: bertrand jouanne - gunnar freyrPublisher: L&#039;ippocampoISBN: 9788867227617\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:38:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/islanda-piccolo-atlante-edonista-jouanne-freyr-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"527\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;25,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\\\/\",\"name\":\"islanda (piccolo atlante edonista) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/islanda-piccolo-atlante-edonista-jouanne-freyr-3.jpg\",\"datePublished\":\"2023-10-04T11:19:14+00:00\",\"dateModified\":\"2026-05-08T22:38:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/islanda-piccolo-atlante-edonista-jouanne-freyr-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/islanda-piccolo-atlante-edonista-jouanne-freyr-3.jpg\",\"width\":527,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"islanda (piccolo atlante edonista)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"25.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788867227617\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"islanda (piccolo atlante edonista) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\/","og_locale":"en_US","og_type":"article","og_title":"islanda (piccolo atlante edonista)","og_description":"Author: bertrand jouanne - gunnar freyrPublisher: L'ippocampoISBN: 9788867227617","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:38:43+00:00","og_image":[{"width":527,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/islanda-piccolo-atlante-edonista-jouanne-freyr-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;25,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\/","name":"islanda (piccolo atlante edonista) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/islanda-piccolo-atlante-edonista-jouanne-freyr-3.jpg","datePublished":"2023-10-04T11:19:14+00:00","dateModified":"2026-05-08T22:38:43+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/islanda-piccolo-atlante-edonista-jouanne-freyr-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/islanda-piccolo-atlante-edonista-jouanne-freyr-3.jpg","width":527,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/islanda-piccolo-atlante-edonista-bertrand-jouanne-gunnar-freyr-9788867227617\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"islanda (piccolo atlante edonista)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"25.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788867227617","product_condition":"new"},"df_price":25,"df_sale_price":"","df_regular_price":25,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/islanda-piccolo-atlante-edonista-jouanne-freyr-3-226x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/121624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=121624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/135160"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=121624"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=121624"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=121624"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=121624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}