{"id":119250,"date":"2024-06-06T14:36:10","date_gmt":"2024-06-06T12:36:10","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/herman-melville-lewis-mumford-9791280635365\/"},"modified":"2026-05-09T00:28:21","modified_gmt":"2026-05-08T22:28:21","slug":"herman-melville-lewis-mumford-9791280635365","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/herman-melville-lewis-mumford-9791280635365\/","title":{"rendered":"herman melville"},"content":{"rendered":"<p><strong>Quando <em>Melville <\/em>mor&igrave;, nel 1891, la rivista letteraria <em>The Critic<\/em> non sapeva nemmeno chi fosse<\/strong>. La scoperta di quello che Mumford definisce &laquo;<em>il pi&ugrave; grande scrittore creativo che l&rsquo;America abbia prodotto, la cui epopea, Moby Dick, &egrave; uno dei pi&ugrave; alti monumenti poetici della lingua inglese<\/em>&raquo; &egrave; opera del XX Secolo.<\/p>\n<p>Melville &egrave; dunque vivo, e <strong>ancor oggi la sua opera ci tocca in profondit&agrave;<\/strong> non perch&eacute; abbia descritto gli arcobaleni dei Mari del Sud, o corretto gli abusi d&rsquo;autorit&agrave; della Marina degli Stati Uniti, ma vive invece perch&eacute; <strong>affront&ograve; certi grandi dilemmi della vita spirituale dell&rsquo;uomo<\/strong>, e cercando di dare una risposta, ne sond&ograve; il fondo. <strong>Abbandon&ograve; il mondo addobbato e ovattato della convenzione, e affront&ograve; la nudit&agrave; della vita, dalla morte, dell&rsquo;energia, del male, dell&rsquo;amore, dell&rsquo;eternit&agrave;<\/strong>: scost&ograve; i confortevoli drappeggi dei salotti vittoriani rivelando l&rsquo;oscura notte, pallidamente rischiarata dalle luci di antiche stelle. Volt&ograve; le spalle a una carriera felice e fortunata per tuffarsi nelle fredde, nere profondit&agrave; dello spirito, le profondit&agrave; dell&rsquo;oceano senza sole; e pur avendo dimostrato che non si poteva vivere in quelle condizioni, riport&ograve; nei meschini trionfi dell&rsquo;epoca quell&rsquo;unico elemento di cui essa mancava completamente: il senso tragico della vita; il senso che il pi&ugrave; alto dei voli umani si libra sopra un abisso inconquistato e forse inconquistabile.<\/p>\n<p>Edizione: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>lewis mumford<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>manzoni editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9791280635365<\/p>\n","protected":false},"featured_media":119248,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2803],"product_tag":[],"class_list":{"0":"post-119250","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biography-and-memories","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>herman melville - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/herman-melville-lewis-mumford-9791280635365\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"herman melville\" \/>\n<meta property=\"og:description\" content=\"Author: lewis mumfordPublisher: manzoni editoreISBN: 9791280635365\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/herman-melville-lewis-mumford-9791280635365\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:28:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/herman-melville-mumford.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"722\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;33,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/herman-melville-lewis-mumford-9791280635365\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/herman-melville-lewis-mumford-9791280635365\\\/\",\"name\":\"herman melville - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/herman-melville-lewis-mumford-9791280635365\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/herman-melville-lewis-mumford-9791280635365\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/herman-melville-mumford.jpg\",\"datePublished\":\"2024-06-06T12:36:10+00:00\",\"dateModified\":\"2026-05-08T22:28:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/herman-melville-lewis-mumford-9791280635365\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/herman-melville-lewis-mumford-9791280635365\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/herman-melville-lewis-mumford-9791280635365\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/herman-melville-mumford.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/herman-melville-mumford.jpg\",\"width\":500,\"height\":722},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/herman-melville-lewis-mumford-9791280635365\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"herman melville\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"33.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9791280635365\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"herman melville - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/herman-melville-lewis-mumford-9791280635365\/","og_locale":"en_US","og_type":"article","og_title":"herman melville","og_description":"Author: lewis mumfordPublisher: manzoni editoreISBN: 9791280635365","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/herman-melville-lewis-mumford-9791280635365\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:28:21+00:00","og_image":[{"width":500,"height":722,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/herman-melville-mumford.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;33,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/herman-melville-lewis-mumford-9791280635365\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/herman-melville-lewis-mumford-9791280635365\/","name":"herman melville - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/herman-melville-lewis-mumford-9791280635365\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/herman-melville-lewis-mumford-9791280635365\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/herman-melville-mumford.jpg","datePublished":"2024-06-06T12:36:10+00:00","dateModified":"2026-05-08T22:28:21+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/herman-melville-lewis-mumford-9791280635365\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/herman-melville-lewis-mumford-9791280635365\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/herman-melville-lewis-mumford-9791280635365\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/herman-melville-mumford.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/herman-melville-mumford.jpg","width":500,"height":722},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/herman-melville-lewis-mumford-9791280635365\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"herman melville"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"33.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9791280635365","product_condition":"new"},"df_price":33,"df_sale_price":"","df_regular_price":33,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/herman-melville-mumford-208x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/119250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=119250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/119248"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=119250"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=119250"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=119250"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=119250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}