{"id":118610,"date":"2024-05-23T15:20:45","date_gmt":"2024-05-23T13:20:45","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\/"},"modified":"2026-05-09T00:29:08","modified_gmt":"2026-05-08T22:29:08","slug":"moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\/","title":{"rendered":"moby dick &#8211; the white whale"},"content":{"rendered":"<p><strong>Stampa Fine Art su tela firmata a mano<\/strong> che riproduce <strong><em>Moby Dick<\/em><\/strong>, la protagonista dell&#8217;omonimo romanzo di <em>Herman Melville<\/em>, braccata dal <em>Capitano Achab<\/em> e dall&#8217;equipaggio della baleniera <em>Pequod<\/em>.<\/p>\n<p>Misura: <strong>cm 25x25x4<\/strong><\/p>\n<p>Accompagnata da un <strong>certificato di autenticit&agrave;<\/strong> firmato a mano.<\/p>\n<p><strong><em>Raffaele Pentasuglia<\/em><\/strong> &egrave; figlio d&rsquo;arte. Dopo la laurea in Fisica a Milano, riscopre la creta e la scultura e decide di tornare a <strong>Matera <\/strong>per intraprendere la carriera di scultore, proseguendo cos&igrave; una <strong>lunga tradizione familiare strettamente legata all&rsquo;arte e all&rsquo;artigianato<\/strong>. Insieme al padre amplia il laboratorio bottega dove si dedica alla lavorazione della ceramica e della cartapesta, producendo <strong>lavori ispirati sia alla tradizione locale che all&rsquo;illustrazione e al fumetto contemporaneo<\/strong>.<\/p>\n<p>I suoi temi prediletti sono il mondo fantastico popolato da gnomi e fattucchiere della tradizione magico-popolare Lucana o dai personaggi della letteratura &ldquo;tolkeniana&rdquo;. Sempre sul<strong> filone letterario<\/strong> si inseriscono i suoi recenti lavori dedicati al capolavoro di <em>Melville<\/em>, <em><strong>Moby Dick<\/strong><\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>raffaele pentasuglia<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>bottega d&#8217;arte pentasuglia<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1716470444<\/p>\n","protected":false},"featured_media":120061,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2443],"product_tag":[],"class_list":{"0":"post-118610","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-literary-framework","7":"product_shipping_class-packaging","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>moby dick - the white whale - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"moby dick - the white whale\" \/>\n<meta property=\"og:description\" content=\"Author: raffaele pentasugliaManufacturer: bottega d&#039;arte pentasugliaISBN: LDM1716470444\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:29:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/the-white-whale-25x25-raffaele-pentasuglia-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"707\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;110,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\\\/\",\"name\":\"moby dick - the white whale - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/the-white-whale-25x25-raffaele-pentasuglia-3.jpg\",\"datePublished\":\"2024-05-23T13:20:45+00:00\",\"dateModified\":\"2026-05-08T22:29:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/the-white-whale-25x25-raffaele-pentasuglia-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/the-white-whale-25x25-raffaele-pentasuglia-3.jpg\",\"width\":707,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"moby dick &#8211; the white whale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"110.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1716470444\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"moby dick - the white whale - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\/","og_locale":"en_US","og_type":"article","og_title":"moby dick - the white whale","og_description":"Author: raffaele pentasugliaManufacturer: bottega d'arte pentasugliaISBN: LDM1716470444","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:29:08+00:00","og_image":[{"width":707,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/the-white-whale-25x25-raffaele-pentasuglia-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;110,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\/","name":"moby dick - the white whale - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/the-white-whale-25x25-raffaele-pentasuglia-3.jpg","datePublished":"2024-05-23T13:20:45+00:00","dateModified":"2026-05-08T22:29:08+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/the-white-whale-25x25-raffaele-pentasuglia-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/the-white-whale-25x25-raffaele-pentasuglia-3.jpg","width":707,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/moby-dick-the-white-whale-raffaele-pentasuglia-ldm1716470444\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"moby dick &#8211; the white whale"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"110.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"LDM1716470444","product_condition":"new"},"df_price":110,"df_sale_price":"","df_regular_price":110,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/the-white-whale-25x25-raffaele-pentasuglia-3-300x297.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/118610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=118610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/120061"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=118610"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=118610"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=118610"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=118610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}