{"id":117239,"date":"2024-04-17T17:08:26","date_gmt":"2024-04-17T15:08:26","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/sea-paradise-eleonora-lombardo-9788838946226\/"},"modified":"2026-05-09T00:30:34","modified_gmt":"2026-05-08T22:30:34","slug":"sea-paradise-eleonora-lombardo-9788838946226","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/sea-paradise-eleonora-lombardo-9788838946226\/","title":{"rendered":"sea paradise"},"content":{"rendered":"<p><strong>Due donne si apprestano a salire sulla Sea Paradise, una nave da crociera capace di regalare un&#8217;esperienza unica e travolgente a migliaia di passeggeri<\/strong>. Ogni desiderio, ogni vizio o virt&ugrave;, pu&ograve; trovare soddisfazione, tutti i sensi saranno esauditi. Pranzi e cene ineguagliabili accompagnati da vini e liquori sopraffini, assistenti personali pronti ad accogliere qualunque richiesta, che sia spirituale o carnale, frivola o ascetica. <strong>Tutto luccica, abbaglia, seduce<\/strong>, nelle cabine curatissime, tra i ponti a picco sull&#8217;oceano, nei giardini sospesi sull&#8217;orizzonte.<\/p>\n<p>Elvira e Amanda hanno settant&#8217;anni, sono amiche da decenni, ed &egrave; la loro prima avventura sulla Sea Paradise. <strong>Come tutti gli altri loro coetanei che si trovano sulla nave, hanno sottoscritto un protocollo rigido e apparentemente perfetto, condizione necessaria per accedere a questa crociera che non ha un prezzo, perch&eacute; offerta in dono dallo Stato ai cittadini che accettano di intraprendere un viaggio che sar&agrave; forse l&#8217;ultimo<\/strong>. Prima di andare in pensione Elvira ha avuto un marito, ha lavorato come formatrice, adesso &egrave; intorpidita dal passare del tempo. Ha deciso di imbarcarsi per non lasciare da sola Amanda, l&#8217;amica imprevedibile e voluttuosa, intensa e volubile, aggrappata a un presente che sembra non avere memoria. Questo &egrave; il loro viaggio, staranno sempre assieme, pensa Elvira. Ma non potr&agrave; essere cos&igrave;, e forse &egrave; un bene.<\/p>\n<p>A bordo della Sea Paradise non circola denaro, non esistono deboli o forti, privilegiati o esclusi, quasi si fosse realizzato un ideale di equit&agrave; sociale. Ma <strong>dietro il sogno dorato e abbagliante c&#8217;&egrave; il buio: tutti sanno che prima o poi, in questo o nel viaggio successivo, l&#8217;oscurit&agrave; arriver&agrave;<\/strong>.<\/p>\n<p>Eleonora Lombardo scrive un romanzo in cui far brillare l&#8217;invenzione e la fantasia, le sorprese e gli stupori, e lo ordisce con fili robusti &#8211; palesi e occulti &#8211; di verit&agrave;. Amicizia e poesia, memoria e libert&agrave;, lo stordimento della saziet&agrave; e la fame del rischio sono il canto e il contrappunto che sostengono le due donne di questa storia, infinitamente giovani, pronte a cambiare e a trasformarsi per essere sempre diverse, sempre nuove, sempre vive.<\/p>\n<p>Edizione: 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>eleonora lombardo<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Sellerio Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788838946226<\/p>\n","protected":false},"featured_media":117237,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2809],"product_tag":[],"class_list":{"0":"post-117239","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-novels","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>sea paradise - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/sea-paradise-eleonora-lombardo-9788838946226\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sea paradise\" \/>\n<meta property=\"og:description\" content=\"Author: eleonora lombardoPublisher: Sellerio EditoreISBN: 9788838946226\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/sea-paradise-eleonora-lombardo-9788838946226\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:30:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sea-paradise-lombardo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"772\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;16,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sea-paradise-eleonora-lombardo-9788838946226\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sea-paradise-eleonora-lombardo-9788838946226\\\/\",\"name\":\"sea paradise - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sea-paradise-eleonora-lombardo-9788838946226\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sea-paradise-eleonora-lombardo-9788838946226\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sea-paradise-lombardo.jpg\",\"datePublished\":\"2024-04-17T15:08:26+00:00\",\"dateModified\":\"2026-05-08T22:30:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sea-paradise-eleonora-lombardo-9788838946226\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sea-paradise-eleonora-lombardo-9788838946226\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sea-paradise-eleonora-lombardo-9788838946226\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sea-paradise-lombardo.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sea-paradise-lombardo.jpg\",\"width\":500,\"height\":772},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sea-paradise-eleonora-lombardo-9788838946226\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"sea paradise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"16.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788838946226\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"sea paradise - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/sea-paradise-eleonora-lombardo-9788838946226\/","og_locale":"en_US","og_type":"article","og_title":"sea paradise","og_description":"Author: eleonora lombardoPublisher: Sellerio EditoreISBN: 9788838946226","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/sea-paradise-eleonora-lombardo-9788838946226\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:30:34+00:00","og_image":[{"width":500,"height":772,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sea-paradise-lombardo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;16,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sea-paradise-eleonora-lombardo-9788838946226\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/sea-paradise-eleonora-lombardo-9788838946226\/","name":"sea paradise - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sea-paradise-eleonora-lombardo-9788838946226\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sea-paradise-eleonora-lombardo-9788838946226\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sea-paradise-lombardo.jpg","datePublished":"2024-04-17T15:08:26+00:00","dateModified":"2026-05-08T22:30:34+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sea-paradise-eleonora-lombardo-9788838946226\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/sea-paradise-eleonora-lombardo-9788838946226\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sea-paradise-eleonora-lombardo-9788838946226\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sea-paradise-lombardo.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sea-paradise-lombardo.jpg","width":500,"height":772},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sea-paradise-eleonora-lombardo-9788838946226\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"sea paradise"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"16.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788838946226","product_condition":"new"},"df_price":16,"df_sale_price":"","df_regular_price":16,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sea-paradise-lombardo-194x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/117239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=117239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/117237"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=117239"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=117239"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=117239"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=117239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}