{"id":116004,"date":"2024-03-21T15:19:08","date_gmt":"2024-03-21T14:19:08","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\/"},"modified":"2026-05-09T00:31:50","modified_gmt":"2026-05-08T22:31:50","slug":"acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\/","title":{"rendered":"acrylic on canvas &#8220;acqua #2&#8221;"},"content":{"rendered":"<p>Acrylic on canvas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>20x20x3,5 cm<\/p>\n<p class=\"autore\"><span>Author: <\/span>clara luminoso<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>clara luminoso<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1711030747<\/p>\n","protected":false},"featured_media":146759,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2436],"product_tag":[],"class_list":{"0":"post-116004","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-paintings","7":"product_shipping_class-packaging","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>acrylic on canvas &quot;acqua #2&quot; - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"acrylic on canvas &quot;acqua #2&quot;\" \/>\n<meta property=\"og:description\" content=\"Subtitle: 20x20x3,5 cmAuthor: clara luminosoManufacturer: clara luminosoISBN: LDM1711030747\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:31:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/acrilico-su-tela-acqua-2-clara-luminoso-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;100,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\\\/\",\"name\":\"acrylic on canvas \\\"acqua #2\\\" - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/acrilico-su-tela-acqua-2-clara-luminoso-3.jpg\",\"datePublished\":\"2024-03-21T14:19:08+00:00\",\"dateModified\":\"2026-05-08T22:31:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/acrilico-su-tela-acqua-2-clara-luminoso-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/acrilico-su-tela-acqua-2-clara-luminoso-3.jpg\",\"width\":700,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"acrylic on canvas &#8220;acqua #2&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"100.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1711030747\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"acrylic on canvas \"acqua #2\" - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\/","og_locale":"en_US","og_type":"article","og_title":"acrylic on canvas \"acqua #2\"","og_description":"Subtitle: 20x20x3,5 cmAuthor: clara luminosoManufacturer: clara luminosoISBN: LDM1711030747","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:31:50+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/acrilico-su-tela-acqua-2-clara-luminoso-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;100,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\/","name":"acrylic on canvas \"acqua #2\" - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/acrilico-su-tela-acqua-2-clara-luminoso-3.jpg","datePublished":"2024-03-21T14:19:08+00:00","dateModified":"2026-05-08T22:31:50+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/acrilico-su-tela-acqua-2-clara-luminoso-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/acrilico-su-tela-acqua-2-clara-luminoso-3.jpg","width":700,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/acrylic-on-canvas-acqua-2-clara-luminoso-ldm1711030747\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"acrylic on canvas &#8220;acqua #2&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"100.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1711030747","product_condition":"new"},"df_price":100,"df_sale_price":"","df_regular_price":100,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/acrilico-su-tela-acqua-2-clara-luminoso-3-300x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/116004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=116004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/146759"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=116004"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=116004"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=116004"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=116004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}