{"id":111614,"date":"2023-12-17T15:57:32","date_gmt":"2023-12-17T14:57:32","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/pesce-di-legno-con-galleggiante-da-appendere-ldm1702825050\/"},"modified":"2026-07-11T00:54:37","modified_gmt":"2026-07-10T22:54:37","slug":"pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\/","title":{"rendered":"pesce di legno con galleggiante da appendere"},"content":{"rendered":"<p>Claudia si &egrave; <strong>laureata in biologia<\/strong> a Milano e ha una <strong>passione sfrenata<\/strong> per gli <strong>ambienti acquatici<\/strong>, per gli <strong>animali in generale<\/strong> e, soprattutto, per le <strong>balene<\/strong>; le produce in ogni forma e dimensione, da parete e da appoggio, recuperando <strong>vecchie assi di legno abbandonate sulle spiagge<\/strong> che incontra lungo il suo vagabondare&hellip; contribuisce, cos&igrave;, a migliorare l&rsquo;aspetto del nostro ecosistema costiero e del nostro amato mare!<\/p>\n<p>Pezzo unico.<\/p>\n<p>Prodotto artigianale.<\/p>\n<p>Made in Italy.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 36&#215;2,5 &#8211; h 4,5 cm<\/p>\n<p class=\"autore\"><span>Author: <\/span>claudia riva<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>once upon a whale<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1702825050<\/p>\n","protected":false},"featured_media":152292,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2902,2904],"product_tag":[],"class_list":{"0":"post-111614","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-wooden-marine-animals","7":"product_cat-other-animals","8":"product_shipping_class-packaging","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>pesce di legno con galleggiante da appendere - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"pesce di legno con galleggiante da appendere\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 36x2,5 - h 4,5 cmAuthor: claudia rivaManufacturer: once upon a whaleISBN: LDM1702825050\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T22:54:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/pesce-di-legno-con-galleggiante-da-appendere-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"933\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;22,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\\\/\",\"name\":\"pesce di legno con galleggiante da appendere - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/pesce-di-legno-con-galleggiante-da-appendere-3.jpg\",\"datePublished\":\"2023-12-17T14:57:32+00:00\",\"dateModified\":\"2026-07-10T22:54:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/pesce-di-legno-con-galleggiante-da-appendere-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/pesce-di-legno-con-galleggiante-da-appendere-3.jpg\",\"width\":933,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"pesce di legno con galleggiante da appendere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"22.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1702825050\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"pesce di legno con galleggiante da appendere - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\/","og_locale":"en_US","og_type":"article","og_title":"pesce di legno con galleggiante da appendere","og_description":"Subtitle: cm 36x2,5 - h 4,5 cmAuthor: claudia rivaManufacturer: once upon a whaleISBN: LDM1702825050","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T22:54:37+00:00","og_image":[{"width":933,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/pesce-di-legno-con-galleggiante-da-appendere-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;22,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\/","name":"pesce di legno con galleggiante da appendere - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/pesce-di-legno-con-galleggiante-da-appendere-3.jpg","datePublished":"2023-12-17T14:57:32+00:00","dateModified":"2026-07-10T22:54:37+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/pesce-di-legno-con-galleggiante-da-appendere-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/pesce-di-legno-con-galleggiante-da-appendere-3.jpg","width":933,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/pesce-di-legno-con-galleggiante-da-appendere-claudia-riva-ldm1702825050\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"pesce di legno con galleggiante da appendere"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"22.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1702825050","product_condition":"new"},"df_price":22,"df_sale_price":"","df_regular_price":22,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/pesce-di-legno-con-galleggiante-da-appendere-3-300x225.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/111614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=111614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/152292"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=111614"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=111614"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=111614"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=111614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}