{"id":105495,"date":"2023-09-18T12:14:23","date_gmt":"2023-09-18T10:14:23","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/senza-categoria\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\/"},"modified":"2026-07-15T00:29:24","modified_gmt":"2026-07-14T22:29:24","slug":"l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\/","title":{"rendered":"l&#8217;arte del sushi"},"content":{"rendered":"<p><strong>Un punto di vista originale e completo per scoprire il valore e i significati che si celano dietro al sushi e al suo mondo<\/strong>.<\/p>\n<p>Il volume si rivolge agli <strong>appassionati della cucina e della cultura orientali<\/strong>, oltre che ai curiosi desiderosi di approfondire la conoscenza di quello che non &egrave; semplicemente un &#8220;cibo&#8221;, ma il <strong>simbolo della cultura gastronomica giapponese<\/strong>.<\/p>\n<p>Ad accompagnarci in questo viaggio gastro culturale, le penne di esperti che attraverso brevi ma prestigiosi saggi ci aiutano a <strong>comprendere e conoscere meglio i segreti di un piatto semplice solo all&#8217;apparenza<\/strong>, che &egrave; stato capace di sedurre il mondo. <strong>Storia, geografia, tradizioni e riti, economia, cinema e letteratura<\/strong>, ma anche il rapporto tra il sushi e l&#8217;Italia e il sushi d&#8217;autore, quello dei grandi chef, sono alcuni degli argomenti affrontati in questo volume.<\/p>\n<p>Arricchiscono il manuale <strong>fotografie, disegni, tavole di manga originali e schede di approfondimento<\/strong> che aiutano il lettore a orientarsi e a soddisfare le curiosit&agrave;.<\/p>\n<p>Per comprendere che ci&ograve; che mangiamo &egrave; anche la storia racchiusa in un boccone.<\/p>\n<p>Edizione: 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Sottotitolo: <\/span>un viaggio gastroculturale alla scoperta del piatto simbolo della cucina giapponese e del suo mondo<\/p>\n<p class=\"autore\"><span>Autore: <\/span>a cura di stefania viti<\/p>\n<p class=\"editore\"><span>Editore: <\/span>Giangiacomo Feltrinelli Editore<\/p>\n","protected":false},"featured_media":105493,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2306],"product_tag":[],"class_list":{"0":"post-105495","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cucina-di-mare","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>l&#039;arte del sushi - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"l&#039;arte del sushi\" \/>\n<meta property=\"og:description\" content=\"Sottotitolo: un viaggio gastroculturale alla scoperta del piatto simbolo della cucina giapponese e del suo mondoAutore: a cura di stefania vitiEditore: Giangiacomo Feltrinelli Editore\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T22:29:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/arte-del-sushi-viti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;12,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\\\/\",\"name\":\"l'arte del sushi - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/arte-del-sushi-viti.jpg\",\"datePublished\":\"2023-09-18T10:14:23+00:00\",\"dateModified\":\"2026-07-14T22:29:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/arte-del-sushi-viti.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/arte-del-sushi-viti.jpg\",\"width\":500,\"height\":730},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"l&#8217;arte del sushi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"12.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788858046982\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"l'arte del sushi - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\/","og_locale":"en_US","og_type":"article","og_title":"l'arte del sushi","og_description":"Sottotitolo: un viaggio gastroculturale alla scoperta del piatto simbolo della cucina giapponese e del suo mondoAutore: a cura di stefania vitiEditore: Giangiacomo Feltrinelli Editore","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-14T22:29:24+00:00","og_image":[{"width":500,"height":730,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/arte-del-sushi-viti.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;12,90","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\/","name":"l'arte del sushi - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/arte-del-sushi-viti.jpg","datePublished":"2023-09-18T10:14:23+00:00","dateModified":"2026-07-14T22:29:24+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/arte-del-sushi-viti.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/arte-del-sushi-viti.jpg","width":500,"height":730},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-arte-del-sushi-a-cura-di-stefania-viti-9788858046982\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"l&#8217;arte del sushi"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"12.90","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788858046982","product_condition":"new"},"df_price":12.9,"df_sale_price":"","df_regular_price":12.9,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/arte-del-sushi-viti-205x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/105495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=105495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/105493"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=105495"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=105495"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=105495"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=105495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}