{"id":103755,"date":"2023-07-27T17:19:07","date_gmt":"2023-07-27T15:19:07","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\/"},"modified":"2026-07-11T01:03:16","modified_gmt":"2026-07-10T23:03:16","slug":"i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\/","title":{"rendered":"i rocca di loano e il secolo d&#8217;oro del grano e dei velieri"},"content":{"rendered":"<p><strong>Loano<\/strong>, il borgo col nome pi&ugrave; dissonante del ponente ligure, fu <strong>fondata nel Trecento dai Doria<\/strong> per motivi mai chiariti se non che &#8220;dovevano avere il loro interesse&#8221;, trasferendola al mare dall&#8217;insediamento originale di cui si sono perse le tracce, ma probabilmente sistemato sulle alture per difendersi dai pirati musulmani tipici di quei tempi.<\/p>\n<p>Forse i Doria vollero una <strong>posizione strategica per il commercio<\/strong> anche perch&eacute; Loano fu costruita vicino ai Portiglioli, la localit&agrave; meno battuta dal libeccio. In pi&ugrave; Loano era vicina al torrente, sopra una falda d&#8217;acqua dolce e, una volta cinta di mura, era certo pi&ugrave; difendibile di quanto non fossero un gran numero di abitazioni e di villaggi sparpagliati.<\/p>\n<p>La costruzione delle mura, ufficialmente, venne fatta un paio di secoli dopo, ma nulla vieta di immaginare che in qualche modo fossero state edificate subito per proteggere l&#8217;abitato. L&#8217;impegno iniziale prevedeva che i Doria regalassero il terreno e i materiali da costruzioni e che i loanesi, in cambio, fornissero frutta, ortaggi e manodopera gratuita per alcuni giorni all&#8217;anno. Dopo duecento anni i Doria cedettero Loano ai Fieschi per motivi economici ma poi, nel 1547, il fallimento della congiura dei Fieschi cambi&ograve; tutto: Loano ritorn&ograve; ai Doria come contea e, dal 1575 al 1606, fu governata da Gianandrea I Doria, a cui sono attribuite le maggiori opere: il palazzo, le mura, alcune chiese e conventi. Di l&igrave; in poi Loano continu&ograve; ad essere nominalmente governata dai Doria sempre pi&ugrave; assenti. Nel 1653, l&#8217;eredit&agrave; pass&ograve; a Giovanni Andrea III che spos&ograve; la romana Anna Pamphili e si trasfer&igrave; a Roma dove mor&igrave; nel 1637 senza essere mai stato a Loano. Da quel momento Loano diventa un feudo dei Savoia, le pretese dei feudatari si allentano finch&eacute; si arriva alla rivoluzione francese e all&#8217;abolizione dei privilegi feudali.<\/p>\n<p>Loano, dunque, <strong>per quasi seicento anni fu un paese di pescatori, di marinai e di contadini poveri e privi di prospettive.<\/strong> Ma <strong>verso il 1785 inizia l&#8217;epoca del commercio del grano<\/strong>, con la &#8220;<strong>Ragione di Commercio Fratelli Rocca<\/strong>&#8221; che va a comprare il grano in Russia, lo trasporta in Europa e l&igrave; lo vende. <strong>Si arricchisce, compra tutte le propriet&agrave; Doria di Loano, crea una flotta di cinquanta navi fabbricate proprio a Loano e i loanesi saranno gli equipaggi e i comandanti<\/strong>. Durer&agrave; fino al 1861 quando fallisce, per un concorso di circostanze.<\/p>\n<p>Le fortune dei Rocca ripresero nel Novecento, per opera di Agostino, che sopravviver&agrave; al terremoto di Reggio Calabria nel 1908, che parteciper&agrave; alla Prima Guerra Mondiale, che pi&ugrave; tardi diventer&agrave; Amministratore Delegato della Dalmine, che per primo lancer&agrave; la produzione d&#8217;acciaio in Italia e che, dopo la guerra, fonder&agrave; la Techint in Argentina. Facendo il primo passo per una delle industrie pi&ugrave; importanti del mondo, quasi a dimostrare che l&#8217;iniziativa dei Rocca del Settecento non fu solo un caso, ma una vocazione.<\/p>\n<p>Edizione: 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>la storia di loano e del commercio del grano che l&#8217;arricch\u00ec tra il sette e l&#8217;ottocento<\/p>\n<p class=\"autore\"><span>Author: <\/span>filippo bonfiglietti<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Primiceri Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788833003221<\/p>\n","protected":false},"featured_media":128771,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2803,3018],"product_tag":[],"class_list":{"0":"post-103755","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biography-and-memories","7":"product_cat-tall-ships","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>i rocca di loano e il secolo d&#039;oro del grano e dei velieri - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"i rocca di loano e il secolo d&#039;oro del grano e dei velieri\" \/>\n<meta property=\"og:description\" content=\"Subtitle: la storia di loano e del commercio del grano che l&#039;arricch\u00ec tra il sette e l&#039;ottocentoAuthor: filippo bonfigliettiPublisher: Primiceri EditoreISBN: 9788833003221\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T23:03:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-bonfiglietti-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"712\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;20,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\\\/\",\"name\":\"i rocca di loano e il secolo d'oro del grano e dei velieri - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-bonfiglietti-1.jpg\",\"datePublished\":\"2023-07-27T15:19:07+00:00\",\"dateModified\":\"2026-07-10T23:03:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-bonfiglietti-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-bonfiglietti-1.jpg\",\"width\":500,\"height\":712},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"i rocca di loano e il secolo d&#8217;oro del grano e dei velieri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"20.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788833003221\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"i rocca di loano e il secolo d'oro del grano e dei velieri - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\/","og_locale":"en_US","og_type":"article","og_title":"i rocca di loano e il secolo d'oro del grano e dei velieri","og_description":"Subtitle: la storia di loano e del commercio del grano che l'arricch\u00ec tra il sette e l'ottocentoAuthor: filippo bonfigliettiPublisher: Primiceri EditoreISBN: 9788833003221","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T23:03:16+00:00","og_image":[{"width":500,"height":712,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-bonfiglietti-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;20,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\/","name":"i rocca di loano e il secolo d'oro del grano e dei velieri - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-bonfiglietti-1.jpg","datePublished":"2023-07-27T15:19:07+00:00","dateModified":"2026-07-10T23:03:16+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-bonfiglietti-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-bonfiglietti-1.jpg","width":500,"height":712},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-filippo-bonfiglietti-9788833003221\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"i rocca di loano e il secolo d&#8217;oro del grano e dei velieri"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"20.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788833003221","product_condition":"new"},"df_price":20,"df_sale_price":"","df_regular_price":20,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rocca-di-loano-e-il-secolo-d-oro-del-grano-e-dei-velieri-bonfiglietti-1-211x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/103755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=103755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/128771"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=103755"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=103755"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=103755"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=103755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}