{"id":103694,"date":"2023-08-09T16:40:05","date_gmt":"2023-08-09T14:40:05","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\/"},"modified":"2026-05-09T00:40:17","modified_gmt":"2026-05-08T22:40:17","slug":"carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\/","title":{"rendered":"carta delle zone turistiche d&#8217;italia &#8211; la riviera di levante da genova a sestri"},"content":{"rendered":"<p><strong>Carta a colori ripiegata in scala 1:50.000<\/strong> delle zone turistiche d&#8217;Italia della Riviera di Levante da Genova a Sestri edita dal <strong>Touring Club Italiano<\/strong> nel <strong>1929<\/strong>.<\/p>\n<p><strong>Busta a custodia in cartoncino<\/strong> rinforzata da nastro di carta adesiva coevo.<\/p>\n<p>In allegato, un <strong>fascicoletto con l&#8217;indice dei nomi<\/strong> contenuti sulla carta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 79&#215;36,3<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>Touring Club Italiano (TCI)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1691592003<\/p>\n","protected":false},"featured_media":110822,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2461,2398],"product_tag":[],"class_list":{"0":"post-103694","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-modern-antiques","7":"product_cat-street-and-tourist-maps","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>carta delle zone turistiche d&#039;italia - la riviera di levante da genova a sestri - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"carta delle zone turistiche d&#039;italia - la riviera di levante da genova a sestri\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 79x36,3Manufacturer: Touring Club Italiano (TCI)ISBN: LDM1691592003\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:40:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-tci-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1398\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;15,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\\\/\",\"name\":\"carta delle zone turistiche d'italia - la riviera di levante da genova a sestri - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-tci-2.jpg\",\"datePublished\":\"2023-08-09T14:40:05+00:00\",\"dateModified\":\"2026-05-08T22:40:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-tci-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-tci-2.jpg\",\"width\":1398,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"carta delle zone turistiche d&#8217;italia &#8211; la riviera di levante da genova a sestri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"15.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1691592003\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"carta delle zone turistiche d'italia - la riviera di levante da genova a sestri - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\/","og_locale":"en_US","og_type":"article","og_title":"carta delle zone turistiche d'italia - la riviera di levante da genova a sestri","og_description":"Subtitle: cm 79x36,3Manufacturer: Touring Club Italiano (TCI)ISBN: LDM1691592003","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:40:17+00:00","og_image":[{"width":1398,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-tci-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;15,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\/","name":"carta delle zone turistiche d'italia - la riviera di levante da genova a sestri - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-tci-2.jpg","datePublished":"2023-08-09T14:40:05+00:00","dateModified":"2026-05-08T22:40:17+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-tci-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-tci-2.jpg","width":1398,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-ldm1691592003\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"carta delle zone turistiche d&#8217;italia &#8211; la riviera di levante da genova a sestri"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"15.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1691592003","product_condition":"new"},"df_price":15,"df_sale_price":"","df_regular_price":15,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/carta-delle-zone-turistiche-d-italia-la-riviera-di-levante-da-genova-a-sestri-tci-2-300x150.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/103694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=103694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/110822"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=103694"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=103694"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=103694"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=103694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}