{"id":103688,"date":"2023-08-30T15:56:45","date_gmt":"2023-08-30T13:56:45","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\/"},"modified":"2026-05-09T00:40:11","modified_gmt":"2026-05-08T22:40:11","slug":"il-governo-dell-acqua-andrea-rinaldo-9788829719761","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\/","title":{"rendered":"il governo dell&#8217;acqua"},"content":{"rendered":"<p><strong>Il dissesto ecologico &egrave; direttamente connesso al governo dell&rsquo;acqua e dunque la scienza delle costruzioni idrauliche &egrave; la cartina di tornasole per affrontare il dibattito pi&ugrave; ampio sui temi della conservazione e dell&rsquo;uso dell&rsquo;ambiente naturale e costruito<\/strong>.<\/p>\n<p>Le opere e i piani di intervento non dovrebbero avere &ndash; sostiene l&rsquo;autore &ndash; paternit&agrave; ideologica; spesso invece <strong>l&rsquo;ambientalismo militante &egrave; carico di pregiudizi sulle opere dell&rsquo;uomo<\/strong> e sulla loro ingegneria &ndash; quando non funzionale a un sistema di potere trasversale di veto e di azione. D&rsquo;altra parte, <strong>i disastri del fare sono quasi sempre il prodotto di un capitalismo cieco<\/strong>, incapace di vedere nella protezione dell&rsquo;ambiente nemmeno il proprio tornaconto. Ma tali posizioni preconcette, cos&igrave; come ogni tesi sbagliata, non possono servire degnamente alcuna politica ambientale di qualche respiro. <strong>Per ovviare a quanto le rispettive retoriche suggeriscono, &egrave; necessario promuovere nuovi modelli di salvaguardia in cui capitalismo e ambientalismo collaborino<\/strong> nel formare la risposta di una societ&agrave; ai problemi ambientali fondamentali per la sua sopravvivenza. Sbagliando, magari, ma dalla parte della scienza.<\/p>\n<p><strong>Questo libro &egrave; il frutto dell&rsquo;esperienza di uno scienziato per una politica ambientale consapevole<\/strong>; un percorso a ritroso lungo la strada tortuosa verso la coscienza della crisi ecologica e climatica, <strong>con l&rsquo;obiettivo di combattere disinformazione e pregiudizi<\/strong>.<\/p>\n<p><strong>Andrea Rinaldo &egrave; il vincitore dello Stockholm Water Prize 2023<\/strong>, un prestigioso riconoscimento indicato spesso come &#8220;<strong>Il Premio Nobel per l&#8217;acqua<\/strong>&#8221; e che viene assegnato a persone, istituzioni o organizzazioni riconosciuti per i risultati eccezionali nel campo della conservazione delle risorse idriche e dell&#8217;accesso all&#8217;acqua di qualit&agrave; per il maggior numero di persone.<\/p>\n<p>Edizione: 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>ambiente naturale e ambiente costruito<\/p>\n<p class=\"autore\"><span>Author: <\/span>andrea rinaldo<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>marsilio editori<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788829719761<\/p>\n","protected":false},"featured_media":125964,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2981,2977],"product_tag":[],"class_list":{"0":"post-103688","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-culture-and-society","7":"product_cat-environment-and-ecology","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>il governo dell&#039;acqua - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"il governo dell&#039;acqua\" \/>\n<meta property=\"og:description\" content=\"Subtitle: ambiente naturale e ambiente costruitoAuthor: andrea rinaldoPublisher: marsilio editoriISBN: 9788829719761\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:40:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/governo-dell-acqua-rinaldo-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"724\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;25,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\\\/\",\"name\":\"il governo dell'acqua - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/governo-dell-acqua-rinaldo-4.jpg\",\"datePublished\":\"2023-08-30T13:56:45+00:00\",\"dateModified\":\"2026-05-08T22:40:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/governo-dell-acqua-rinaldo-4.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/governo-dell-acqua-rinaldo-4.jpg\",\"width\":500,\"height\":724},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"il governo dell&#8217;acqua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"25.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788829719761\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"il governo dell'acqua - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\/","og_locale":"en_US","og_type":"article","og_title":"il governo dell'acqua","og_description":"Subtitle: ambiente naturale e ambiente costruitoAuthor: andrea rinaldoPublisher: marsilio editoriISBN: 9788829719761","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:40:11+00:00","og_image":[{"width":500,"height":724,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/governo-dell-acqua-rinaldo-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;25,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\/","name":"il governo dell'acqua - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/governo-dell-acqua-rinaldo-4.jpg","datePublished":"2023-08-30T13:56:45+00:00","dateModified":"2026-05-08T22:40:11+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/governo-dell-acqua-rinaldo-4.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/governo-dell-acqua-rinaldo-4.jpg","width":500,"height":724},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-governo-dell-acqua-andrea-rinaldo-9788829719761\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"il governo dell&#8217;acqua"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"25.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788829719761","product_condition":"new"},"df_price":25,"df_sale_price":"","df_regular_price":25,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/governo-dell-acqua-rinaldo-4-207x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/103688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=103688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/125964"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=103688"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=103688"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=103688"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=103688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}