{"id":103486,"date":"2023-09-06T15:10:31","date_gmt":"2023-09-06T13:10:31","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\/"},"modified":"2026-05-09T00:39:52","modified_gmt":"2026-05-08T22:39:52","slug":"rapsodia-blu-luca-sonnino-sorisio-ldm1694005829","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\/","title":{"rendered":"rapsodia blu"},"content":{"rendered":"<p><strong>Raro esemplare della prima edizione di Nautica Editrice del 1991 ristampata nel 2005 in perfetto stato di conservazione. In-4, legatura editoriale con copertina rigida telata azzurra, con impressioni argento al piatto anteriore e al dorso; con cofanetto rigido telato blu rivestito in carta illustrata a colori (con lievi segni del tempo) e sovraccoperta in carta plastificata illustrata a colori con alette; con risguardi neri (con etichetta coeva della Libreria Internazionale Il Mare al risguardo posteriore), occhiello illustrato in nero e antiporta illustrata a colori; 216 pp., con numerosissime fotografie a colori incorniciate nel testo.<\/strong><\/p>\n<p><strong>Fotografie e ricerca antologica di Luca Sonnino Sorisio.<\/strong><\/p>\n<p><strong>Prefazione di Folco Quilici.<\/strong><\/p>\n<p>Dall&#8217;aletta anteriore:&nbsp;<em>Un inno al mare. RAPSODIA BLU &egrave; un libro dedicato al mare e ai suoi abitanti, una raccolta di poesie e brani di prosa: da Omero a Conrad, da Melville a Hemingway, ai grandi navigatori, scienziati e poeti cui il mare ha ispirato pagine meravigliose. Finalmente in un volume unico, da leggere tutto di un fiato e da sfogliare mille volte, RAPSODIA BLU &egrave;, infatti, soprattutto un&#8217;incredibile collezione di fotografie riprese da LUCA SONNINO SORISIO sopra e sotto la superficie in diversi mari del mondo. E&#8217; una celebrazione attraverso l&#8217;obiettivo di barche stupende, di panorami sottomarini magnifici, delle creature dai colori e forme stupefacenti che li popolano. Un volume da conservare gelosamente e che invita a rispettare, amare, conoscere meglio e, dunque, difendere il mare, ultima frontiera della natura selvaggia.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>il mare in poesia, prosa e fotografia<\/p>\n<p class=\"autore\"><span>Author: <\/span>luca sonnino sorisio<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>nautica editrice<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1694005829<\/p>\n","protected":false},"featured_media":134907,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2621,2608,2646],"product_tag":[],"class_list":{"0":"post-103486","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-picture-books","7":"product_cat-reports-and-essays","8":"product_cat-world-picture-books-tourism","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>rapsodia blu - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"rapsodia blu\" \/>\n<meta property=\"og:description\" content=\"Subtitle: il mare in poesia, prosa e fotografiaAuthor: luca sonnino sorisioPublisher: nautica editriceISBN: LDM1694005829\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:39:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rapsodia-blu-il-mare-in-poesia-prosa-e-fotografia-luca-sonnino-sorisio-nautica-editrice-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"722\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;69,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\\\/\",\"name\":\"rapsodia blu - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/rapsodia-blu-il-mare-in-poesia-prosa-e-fotografia-luca-sonnino-sorisio-nautica-editrice-3.jpg\",\"datePublished\":\"2023-09-06T13:10:31+00:00\",\"dateModified\":\"2026-05-08T22:39:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/rapsodia-blu-il-mare-in-poesia-prosa-e-fotografia-luca-sonnino-sorisio-nautica-editrice-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/rapsodia-blu-il-mare-in-poesia-prosa-e-fotografia-luca-sonnino-sorisio-nautica-editrice-3.jpg\",\"width\":722,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"rapsodia blu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"69.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1694005829\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"rapsodia blu - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\/","og_locale":"en_US","og_type":"article","og_title":"rapsodia blu","og_description":"Subtitle: il mare in poesia, prosa e fotografiaAuthor: luca sonnino sorisioPublisher: nautica editriceISBN: LDM1694005829","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:39:52+00:00","og_image":[{"width":722,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rapsodia-blu-il-mare-in-poesia-prosa-e-fotografia-luca-sonnino-sorisio-nautica-editrice-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;69,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\/","name":"rapsodia blu - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rapsodia-blu-il-mare-in-poesia-prosa-e-fotografia-luca-sonnino-sorisio-nautica-editrice-3.jpg","datePublished":"2023-09-06T13:10:31+00:00","dateModified":"2026-05-08T22:39:52+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rapsodia-blu-il-mare-in-poesia-prosa-e-fotografia-luca-sonnino-sorisio-nautica-editrice-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rapsodia-blu-il-mare-in-poesia-prosa-e-fotografia-luca-sonnino-sorisio-nautica-editrice-3.jpg","width":722,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/rapsodia-blu-luca-sonnino-sorisio-ldm1694005829\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"rapsodia blu"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"69.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1694005829","product_condition":"new"},"df_price":69,"df_sale_price":"","df_regular_price":69,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/rapsodia-blu-il-mare-in-poesia-prosa-e-fotografia-luca-sonnino-sorisio-nautica-editrice-3-300x291.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/103486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=103486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/134907"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=103486"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=103486"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=103486"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=103486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}