{"id":102935,"date":"2023-08-29T13:47:25","date_gmt":"2023-08-29T11:47:25","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/jamaica-vibes-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\/"},"modified":"2026-05-09T00:40:16","modified_gmt":"2026-05-08T22:40:16","slug":"jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\/","title":{"rendered":"Jamaica Vibes (Travel Series)"},"content":{"rendered":"<p>Surely the most stylish and cool island in the Caribbean, <strong>Jamaica<\/strong> is not only the cradle of <strong>reggae<\/strong> but also a favorite destination for <strong>James Bond<\/strong>. While there is no shortage of <strong>luxury villas and white-sand beaches<\/strong>, Jamaica offers something that other destinations lack: <strong>a vibrant culture<\/strong>, wholly its own. Overflowing with character, Jamaica has a strong sense of self, which was shaped over the centuries during its fight for freedom and independence.<\/p>\n<p>This national pride is reflected in the <strong>music, dance, cuisine and literature<\/strong> that originated in Jamaica but has since influenced people across the globe. The legacy of <strong>Bob Marley<\/strong> is intricately linked with the image of Jamaica, leaving an indelible mark on the country and the world. For novelist <strong>Ian Fleming<\/strong>, Jamaica was his creative incubator. At his home, <em>GoldenEye<\/em>, Fleming crafted one of the most well-known characters in the world, James Bond. Travelers can now walk in the footsteps of these titans of creative expression by touring 56 Hope Road in Kingston, Bob Marley&rsquo;s former home, or by staying at <em>GoldenEye<\/em>. Whether you&rsquo;re born and raised on the island, or just on a vacation, Jamaica&rsquo;s influence is undeniable. <strong>Chris Blackwell<\/strong>, founder of Island Records, <strong>contributes a foreword<\/strong> to <em>Jamaica Vibes<\/em>, presenting an intimate, insider portrait of this vibrant island nation and its mesmerizing power.<\/p>\n<p>Edition: 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>Lisa Lovatt-Smith &#8211; Novia McDonald-Whyte<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Assouline<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9781649802255<\/p>\n","protected":false},"featured_media":165141,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2646],"product_tag":[],"class_list":{"0":"post-102935","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-world-picture-books-tourism","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Jamaica Vibes (Travel Series) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jamaica Vibes (Travel Series)\" \/>\n<meta property=\"og:description\" content=\"Author: Lisa Lovatt-Smith - Novia McDonald-WhytePublisher: AssoulineISBN: 9781649802255\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:40:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/jamaica-vibes-lisa-lovatt-smith-novia-mcdonald-whyte-assouline-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;105,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\\\/\",\"name\":\"Jamaica Vibes (Travel Series) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/jamaica-vibes-lisa-lovatt-smith-novia-mcdonald-whyte-assouline-2.jpg\",\"datePublished\":\"2023-08-29T11:47:25+00:00\",\"dateModified\":\"2026-05-08T22:40:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/jamaica-vibes-lisa-lovatt-smith-novia-mcdonald-whyte-assouline-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/jamaica-vibes-lisa-lovatt-smith-novia-mcdonald-whyte-assouline-2.jpg\",\"width\":700,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jamaica Vibes (Travel Series)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"105.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9781649802255\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Jamaica Vibes (Travel Series) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\/","og_locale":"en_US","og_type":"article","og_title":"Jamaica Vibes (Travel Series)","og_description":"Author: Lisa Lovatt-Smith - Novia McDonald-WhytePublisher: AssoulineISBN: 9781649802255","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:40:16+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/jamaica-vibes-lisa-lovatt-smith-novia-mcdonald-whyte-assouline-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;105,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\/","name":"Jamaica Vibes (Travel Series) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/jamaica-vibes-lisa-lovatt-smith-novia-mcdonald-whyte-assouline-2.jpg","datePublished":"2023-08-29T11:47:25+00:00","dateModified":"2026-05-08T22:40:16+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/jamaica-vibes-lisa-lovatt-smith-novia-mcdonald-whyte-assouline-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/jamaica-vibes-lisa-lovatt-smith-novia-mcdonald-whyte-assouline-2.jpg","width":700,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/jamaica-vibes-travel-series-lisa-lovatt-smith-novia-mcdonald-whyte-9781649802255\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Jamaica Vibes (Travel Series)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"105.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9781649802255","product_condition":"new"},"df_price":105,"df_sale_price":"","df_regular_price":105,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/jamaica-vibes-lisa-lovatt-smith-novia-mcdonald-whyte-assouline-2-300x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/102935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=102935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/165141"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=102935"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=102935"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=102935"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=102935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}